{"id":12245,"date":"2013-12-12T10:33:26","date_gmt":"2013-12-12T15:33:26","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=12245"},"modified":"2013-12-12T10:35:44","modified_gmt":"2013-12-12T15:35:44","slug":"farid-ortiz-sigue-siendo-la-sensacion-de-las-mejores-fiestas-del-fin-de-ano","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/farid-ortiz-sigue-siendo-la-sensacion-de-las-mejores-fiestas-del-fin-de-ano\/","title":{"rendered":"Farid Ortiz sigue siendo la sensaci\u00f3n de las mejores fiestas del fin de a\u00f1o"},"content":{"rendered":"<p>Farid Ortiz sigue siendo la sensaci&oacute;n musical de las mejores fiestas en diciembre y este &lsquo;Fin de semana&rsquo; estar&aacute; en los departamentos de Antioquia y C&oacute;rdoba.<\/p>\n<p>El viernes 13 Farid Ortiz y Anuar Garc&iacute;a actuar&aacute;n en Caucasia (Antioquia); el s&aacute;bado 14 en Pueblo Nuevo y el domingo 15 en La Apartada (C&oacute;rdoba).<\/p>\n<p>En estas tres salidas musicales &lsquo;El Rey de los Pueblos&rsquo; interpretar&aacute; el &eacute;xito de diciembre &lsquo;Fin de semana&rsquo; que aclaman todos sus seguidores para prender el &aacute;nimo de las mejores fiestas. La canci&oacute;n sigue en los primeros lugares.<\/p>\n<p>Indiscutiblemente Farid Ortiz, sigue siendo el artista preferido de la gente para animar las mejores despedidas del fin de a&ntilde;o.<\/p>\n<p><strong>Gira musical<\/strong><\/p>\n<p>Viernes 13 de diciembre: Caucasia &ndash; Antioquia<\/p>\n<p>S&aacute;bado 14: Pueblo Nuevo &ndash; C&oacute;rdona<\/p>\n<p>Domingo 15: La Apartada &#8211; C&oacute;rdoba<\/p>\n<p>Contactos de Farid Ortiz &ndash;<\/p>\n<p><strong>SOLAMENTE ESTOS N&Uacute;MEROS SON LOS EXCLUSIVOS PARA CONTRATAR CON FARID ORTIZ<\/strong><\/p>\n<p><strong>Oficina<\/strong><\/p>\n<p><strong>5843424<\/strong><\/p>\n<p><strong>3117631796<\/strong><\/p>\n<p><strong>3176780244<\/strong><\/p>\n<p><strong>3002152852<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Farid Ortiz sigue siendo la sensaci&oacute;n musical de las mejores fiestas en diciembre y este &lsquo;Fin de semana&rsquo; estar&aacute; en los departamentos de Antioquia y C&oacute;rdoba. El viernes 13 Farid Ortiz y Anuar Garc&iacute;a actuar&aacute;n en Caucasia (Antioquia); el s&aacute;bado 14 en Pueblo Nuevo y el domingo 15 en La Apartada (C&oacute;rdoba). En estas tres [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12245"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=12245"}],"version-history":[{"count":3,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12245\/revisions"}],"predecessor-version":[{"id":12247,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12245\/revisions\/12247"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/11827"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=12245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=12245"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=12245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}