{"id":12411,"date":"2014-01-08T06:19:41","date_gmt":"2014-01-08T11:19:41","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=12411"},"modified":"2014-01-08T06:19:41","modified_gmt":"2014-01-08T11:19:41","slug":"peter-manjarres-y-sergio-luis-rodriguez-presentan-en-video-la-plata-no-alcanza","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/peter-manjarres-y-sergio-luis-rodriguez-presentan-en-video-la-plata-no-alcanza\/","title":{"rendered":"Peter Manjarres y Sergio Lu\u00eds Rodr\u00edguez presentan en video &#8216;La plata no alcanza&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">Tras la gran acogida durante toda la temporada decembrina de la canci&oacute;n La Plata No Alcanza, hoy hacemos la presentaci&oacute;n del video oficial de este tema jocoso de la autor&iacute;a de Jorge Adel Iguar&aacute;n.<\/p>\n<p style=\"text-align: justify;\">&nbsp;El rodaje del video se llev&oacute; a cabo en las ciudades&nbsp; de Barranquilla, Cartagena&nbsp; y Valledupar, bajo la direcci&oacute;n de Jos&eacute; Vergara y la participaci&oacute;n del humorista coste&ntilde;o Joselo y la modelo Jennyfer Gonzalez, actores que aprovecharon la tem&aacute;tica graciosa de la canci&oacute;n para dejar plasmada de forma muy caricaturesca la situaci&oacute;n que viven muchas personas diariamente en nuestro pa&iacute;s.<\/p>\n<p style=\"text-align: justify;\">La Organizaci&oacute;n Musical de Peter Manjar&eacute;s y Sergio Luis Rodr&iacute;guez agradecen a todas las personas que se vincularon a este video, m&aacute;s de 50 en total, aportando su alegr&iacute;a e imagen para hacer m&aacute;s divertido este proyecto. A partir de hoy pueden ver en nuestra p&aacute;gina oficial <a href=\"http:\/\/www.petermanjarres.net\">www.petermanjarres.net<\/a> el video La Plata No Alcanza.<\/p>\n<p>&nbsp;Porque definitivamente, LA PLATA NO ALCANZA!!!<\/p>\n<p>\n\t<strong>MANAGER<\/strong><\/p>\n<p><strong>MARCOS TORRES<\/strong><\/p>\n<p><strong>Celular: 315 7338388 &#8211; 300 8140721<\/strong><\/p>\n<p><strong><a href=\"mailto:martovel@hotmail.com\">martovel@hotmail.com<\/a> &#8211; <a href=\"mailto:mtorres@petermanjarres.net\">mtorres@petermanjarres.net<\/a><br \/>\n\tTwitter: @Martovel<br \/>\n\t&nbsp;&nbsp;<br \/>\n\tBUSINESS MANAGER<\/strong><\/p>\n<p><strong>BETO MURGAS JR<\/strong><\/p>\n<p><strong>Celular: 318 7428660 &#8211; 301 660 9670<br \/>\n\t&nbsp;<a href=\"mailto:nbmanager@petermanjarres.net\">nbmanager@petermanjarres.net<\/a> &#8211; <a href=\"mailto:ajmurgas@hotmail.com\">ajmurgas@hotmail.com<\/a><br \/>\n\tTwitter: @BetoMurgas<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>STAGE &amp; COMMUNITY MANAGER<\/strong><\/p>\n<p><strong>BRYAN CUADRO<\/strong><\/p>\n<p><strong>Celular: 317 3650041 &#8211; 304 3817725 &#8211; 317 6668275<\/strong><\/p>\n<p><strong><a href=\"mailto:bryan_cuadro@hotmail.com\">bryan_cuadro@hotmail.com<\/a> &#8211; <a href=\"mailto:stagemanager@petermanjarres.net\">stagemanager@petermanjarres.net<\/a><br \/>\n\tTwitter: @BryanCuadro<br \/>\n\t&nbsp;<br \/>\n\t&nbsp;<br \/>\n\t&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la gran acogida durante toda la temporada decembrina de la canci&oacute;n La Plata No Alcanza, hoy hacemos la presentaci&oacute;n del video oficial de este tema jocoso de la autor&iacute;a de Jorge Adel Iguar&aacute;n. &nbsp;El rodaje del video se llev&oacute; a cabo en las ciudades&nbsp; de Barranquilla, Cartagena&nbsp; y Valledupar, bajo la direcci&oacute;n de Jos&eacute; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12411"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=12411"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12411\/revisions"}],"predecessor-version":[{"id":12413,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12411\/revisions\/12413"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/12412"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=12411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=12411"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=12411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}