{"id":12465,"date":"2014-01-15T06:06:59","date_gmt":"2014-01-15T11:06:59","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=12465"},"modified":"2014-01-15T06:06:59","modified_gmt":"2014-01-15T11:06:59","slug":"farid-ortiz-el-vallenato-sensacional-de-las-fiestas-de-sincelejo","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/farid-ortiz-el-vallenato-sensacional-de-las-fiestas-de-sincelejo\/","title":{"rendered":"Farid Ortiz el vallenato sensacional de las fiestas de Sincelejo"},"content":{"rendered":"<p style=\"text-align: justify;\">Sensacional y espectacular, as&iacute; ser&aacute; el concierto que ofrecer&aacute; Farid Ortiz, &lsquo;El Rey de los Pueblos&rsquo; en las fiestas del 20 de Enero en Sincelejo, donde es el artista vallenato m&aacute;s esperado.<\/p>\n<p style=\"text-align: justify;\">El gran concierto se realizar&aacute; el lunes 20 de enero en medio de la gran expectativa que siempre ha generado este virtuoso artista encargado de cerrar estas festividades que ha reunido a toda la gente festiva de la Costa Caribe y Colombia.<\/p>\n<p style=\"text-align: justify;\">Con su &eacute;xito de carnaval &lsquo;Fin de semana&rsquo;, Farid Ortiz y Anuar Garc&iacute;a, pondr&aacute;n a gozar a los sincelejanos y turistas de esta gran fiesta popular que se ha sentido en todos los barrios de la capital de Sucre.<\/p>\n<p style=\"text-align: justify;\">Farid Ortiz y Anuar Garc&iacute;a inician su gira musical el s&aacute;bado 18 de enero en Ubat&eacute; (Cundinamarca); el domingo 19 estar&aacute; en el corregimiento Ca&ntilde;averal, municipio de Turbaco y el lunes 20 de enero cerrar&aacute;n las fiestas de corralejas de Sincelejo.<\/p>\n<p style=\"text-align: justify;\"><strong>GIRA MUSICAL<\/strong><\/p>\n<p>S&aacute;bado 18: Ubat&eacute; &ndash; Cundinamarca<\/p>\n<p>Domingo 19 de enero: Ca&ntilde;averal &ndash; municipio de Turbaco &#8211; Bol&iacute;var<\/p>\n<p>Lunes20: Fiestas del 20 de Enero de Sincelejo<\/p>\n<p><strong>Oficina<br \/>\n\t5843424<br \/>\n\t3117631796<br \/>\n\t3176780244<br \/>\n\t3002152852<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\n\t&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sensacional y espectacular, as&iacute; ser&aacute; el concierto que ofrecer&aacute; Farid Ortiz, &lsquo;El Rey de los Pueblos&rsquo; en las fiestas del 20 de Enero en Sincelejo, donde es el artista vallenato m&aacute;s esperado. El gran concierto se realizar&aacute; el lunes 20 de enero en medio de la gran expectativa que siempre ha generado este virtuoso artista [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12465"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=12465"}],"version-history":[{"count":2,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12465\/revisions"}],"predecessor-version":[{"id":12467,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12465\/revisions\/12467"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/11827"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=12465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=12465"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=12465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}