{"id":12541,"date":"2014-01-24T05:48:43","date_gmt":"2014-01-24T10:48:43","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=12541"},"modified":"2014-01-24T05:49:53","modified_gmt":"2014-01-24T10:49:53","slug":"12541","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/12541\/","title":{"rendered":"Iv\u00e1n Villaz\u00f3n y Sa\u00fal Lallemand, le cantan a Barranquilla y Puerto LLeras \/ Meta"},"content":{"rendered":"<p style=\"text-align: justify;\">Colombia sigue brind&aacute;ndole muchas satisfacciones a Iv&aacute;n Villaz&oacute;n y Sa&uacute;l Lallemand cada que tienen la oportunidad de visitar ciudades y poblaciones del territorio nacional donde son acogidos con mucho cari&ntilde;o y demostr&aacute;ndole un masivo apoyo en sus presentaciones.<\/p>\n<p style=\"text-align: justify;\">La reciente gira que realizaron en d&iacute;as pasados llev&oacute; a Villaz&oacute;n y Lallemand a tres hermosos lugares de la Costa Atl&aacute;ntica, Sincelejo, Ci&eacute;naga y San Sebasti&aacute;n, donde hicieron su aporte musical para amenizar sus fiestas populares.<\/p>\n<p style=\"text-align: justify;\">Iv&aacute;n Villaz&oacute;n y Sa&uacute;l Lallemand en Sincelejo hicieron parte de un concierto de gran envergadura en el marco de las fiestas del 20 de enero, logrando destacarse como uno de los shows vallenatos m&aacute;s ovacionados por los miles de asistentes, misma respuesta recibieron del p&uacute;blico en las fiestas del Caim&aacute;n en Ci&eacute;naga y en las fiestas patronales de San Sebasti&aacute;n en el Magdalena.<\/p>\n<p style=\"text-align: justify;\">Este fin de semana Barranquilla y Puerto Lleras reciben a Villaz&oacute;n y Lallemand, el viernes actuar&aacute;n en la reci&eacute;n inaugurada Discoteca &ldquo;D&iacute;scolo&rdquo; en Barranquilla y el s&aacute;bado en el Festival de Verano que se llevar&aacute; a cabo en Puerto Lleras en el Meta.<\/p>\n<p style=\"text-align: justify;\">El lunes entrar&aacute;n a los estudios de grabaci&oacute;n Iv&aacute;n Villaz&oacute;n y Sa&uacute;l Lallemand, para dar inici&oacute; a la nueva producci&oacute;n que ser&aacute; lanzada pr&oacute;ximamente y que tanta expectativa ha despertado.<\/p>\n<p style=\"text-align: justify;\"><strong>GIRA MUSICAL<\/strong><\/p>\n<p>Viernes 24 de enero: Discoteca &ldquo;D&iacute;scolo&rdquo; &#8211; Barranquilla<\/p>\n<p>S&aacute;bado 25: Puerto Lleras &#8211; Meta<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Manager<\/strong><br \/>\n\t<strong>JUANK VEGA<\/strong><br \/>\n\tTel&eacute;fonos: <strong>(315) 3804051, (301) 3630069<\/strong><\/p>\n<p>Email: <strong>manager@ivanvillazon.com.co<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Sitio Web: <strong>www.ivanvillazon.com.co<\/strong><\/p>\n<p>Twitter: <strong>@IVANVILLAZON <\/strong><br \/>\n\tInstagram: <strong>@IVANVILLAZON<\/strong><\/p>\n<p>YouTube:<strong> LAVOZTENOR<\/strong><br \/>\n\tFacebook: <strong>LAVOZTENOR<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colombia sigue brind&aacute;ndole muchas satisfacciones a Iv&aacute;n Villaz&oacute;n y Sa&uacute;l Lallemand cada que tienen la oportunidad de visitar ciudades y poblaciones del territorio nacional donde son acogidos con mucho cari&ntilde;o y demostr&aacute;ndole un masivo apoyo en sus presentaciones. La reciente gira que realizaron en d&iacute;as pasados llev&oacute; a Villaz&oacute;n y Lallemand a tres hermosos lugares [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12541"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=12541"}],"version-history":[{"count":3,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12541\/revisions"}],"predecessor-version":[{"id":12544,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12541\/revisions\/12544"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/12542"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=12541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=12541"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=12541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}