{"id":12637,"date":"2014-02-07T05:31:29","date_gmt":"2014-02-07T10:31:29","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=12637"},"modified":"2014-02-07T05:31:38","modified_gmt":"2014-02-07T10:31:38","slug":"alex-manga-y-andres-el-neno-beleno-con-sus-mejores-exitos-en-la-capital-del-mundo-new-york-estados-unidos","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/alex-manga-y-andres-el-neno-beleno-con-sus-mejores-exitos-en-la-capital-del-mundo-new-york-estados-unidos\/","title":{"rendered":"Alex Manga y Andr\u00e9s &#8216;El Neno&#8217; Bele\u00f1o, con sus mejores \u00e9xitos en La Capital del Mundo: New York &#8211; Estados Unidos"},"content":{"rendered":"<p style=\"text-align: justify;\">Se vislumbra que este a&ntilde;o ser&aacute; tan excelente como el anterior para Alex Manga, sobre todo en lo que tiene que ver con su consolidaci&oacute;n a nivel internacional, es uno de los artistas vallenatos con m&aacute;s n&uacute;mero de salidas fuera de Colombia.<\/p>\n<p style=\"text-align: justify;\">Alexen el 2014 continuar&aacute; recorriendo el mundo llevando su show en vivo que es aclamado por multitudes que se deleitan con tantas canciones llenas de sentimiento de su repertorio, lo que le ha permitido que en Norteam&eacute;rica, Centroam&eacute;rica, Suram&eacute;rica y Europa, goc&eacute; de tanta popularidad entre la colonia latina amante del folclor vallenato.<\/p>\n<p style=\"text-align: justify;\">Esta semana Alex Manga, su acordeonero Andr&eacute;s &#39;El Neno&#39; Bele&ntilde;o y el resto de su agrupaci&oacute;n, visitar&aacute;n una vez m&aacute;s los Estados Unidos, su segunda casa, uno de los pa&iacute;ses donde cuentan con mayor n&uacute;mero de seguidores, son esos fans los que permanentemente solicitan su presencia y llenan los espect&aacute;culos en los cuales act&uacute;an y gracias tambi&eacute;n a la confianza que en ellos tienen los empresarios que saben que siempre ser&aacute; todo un &eacute;xito contratarlos.<\/p>\n<p style=\"text-align: justify;\">El s&aacute;bado Alex tiene dos presentaciones que sirven de pre&aacute;mbulo al festejo del d&iacute;a de San Valent&iacute;n, en un mismo d&iacute;a estar&aacute; actuando en New Jersey en el International Club Sport Bar y en New York en Rumba Night Club, como de costumbre se llenar&aacute;n estos escenarios al dispararse la preventa de la boleter&iacute;a durante estos d&iacute;as.<\/p>\n<p style=\"text-align: justify;\"><strong>GIRA MUSICAL<\/strong><\/p>\n<p style=\"text-align: justify;\">S&aacute;bado 8 de febrero: International Club Sport Bar \/ New Jersey, Estados Unidos<\/p>\n<p>S&aacute;bado 8: Rumba Night Club \/ New York, Estados Unidos<\/p>\n<p>Contacto<\/p>\n<p>Colombia \/ Tel&eacute;fonos: (300) 496 8696, (314) 542 8336<\/p>\n<p>Venezuela \/ Tel&eacute;fono: (58 414) 362 7140<\/p>\n<p>Estados Unidos \/ Tel&eacute;fono: (01786) 759 9365<\/p>\n<p>Twitter: @ALEXMANGA1<\/p>\n<p>Facebook: ALEX MANGA<\/p>\n<p>Instagram: @ALEXMANGA1<\/p>\n<p>YouTube: ALEXMANGATV<\/p>\n<p>Website: ALEXMANGA.COM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se vislumbra que este a&ntilde;o ser&aacute; tan excelente como el anterior para Alex Manga, sobre todo en lo que tiene que ver con su consolidaci&oacute;n a nivel internacional, es uno de los artistas vallenatos con m&aacute;s n&uacute;mero de salidas fuera de Colombia. Alexen el 2014 continuar&aacute; recorriendo el mundo llevando su show en vivo que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11589,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12637"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=12637"}],"version-history":[{"count":3,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12637\/revisions"}],"predecessor-version":[{"id":12640,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12637\/revisions\/12640"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/11589"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=12637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=12637"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=12637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}