{"id":12650,"date":"2014-02-10T07:56:50","date_gmt":"2014-02-10T12:56:50","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=12650"},"modified":"2014-02-10T07:56:50","modified_gmt":"2014-02-10T12:56:50","slug":"jorge-celedon-inicia-el-tour-sin-fronteras-por-estados-unidos-del-13-al-16-de-febrero-2014","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/jorge-celedon-inicia-el-tour-sin-fronteras-por-estados-unidos-del-13-al-16-de-febrero-2014\/","title":{"rendered":"Jorge Celed\u00f3n inicia el Tour Sin Fronteras por Estados Unidos del 13 al 16 de febrero 2014"},"content":{"rendered":"<p style=\"text-align: justify;\">Jorge Celed&oacute;n, el &Iacute;dolo Mundial del Vallenato, inicia en la presente semana el Tour <em>Sin Fronteras<\/em> en Estados Unidos con seis espectaculares conciertos del 13 de febrero, en una jornada marat&oacute;nica donde ratificar&aacute; que es el artista vallenato de mayor convocatoria en el pa&iacute;s del norte.<\/p>\n<p style=\"text-align: justify;\">En estos seis conciertos por Virginia, New York, Tampa y el estado La Florida, Jorge Celed&oacute;n y su acordeonero interpretar&aacute;n los &eacute;xitos del &aacute;lbum &lsquo;Sin Fronteras&rsquo; que ha sido de gran impacto en Estados Unidos, logrando posicionar en primeros lugares las canciones: &lsquo;Y ahora te vas&rsquo;, &lsquo;La candela viva&rsquo;, y el reciente sencillo &lsquo;D&iacute;a tras d&iacute;a&rsquo;.<\/p>\n<p style=\"text-align: justify;\">En esta producci&oacute;n participaron estrellas hispanoamericanas y colombianas como Marco Antonio Solis, &lsquo;Tot&oacute; La Momposina&rsquo;, Andr&eacute;s Cepeda, Elvis Crespo, Franco de Vita, Oscar de Le&oacute;n, entre otros.<\/p>\n<p style=\"text-align: justify;\">Asimismo, Celed&oacute;n complacer&aacute; a sus compatriotas y comunidad latina con sus &eacute;xitos internacionales: &lsquo;Ay hombe&rsquo;, &lsquo;Cuatro rosas&rsquo;, &lsquo;Esta vida y &lsquo;La Invitaci&oacute;n&rsquo;, tema insigne que despierta el fervor de los colombianos en el exterior.<\/p>\n<p style=\"text-align: justify;\">El Tour &lsquo;Sin Fronteras&rsquo; de Jorge Celed&oacute;n tendr&aacute; el siguiente recorrido:<\/p>\n<p style=\"text-align: justify;\">Jueves 13 de febrero: The Palace &#8211; Virginia<\/p>\n<p style=\"text-align: justify;\">Viernes 14: La Boom &ndash; Queens<\/p>\n<p style=\"text-align: justify;\">Viernes 14: Tette Club &ndash; New York<\/p>\n<p style=\"text-align: justify;\">S&aacute;bado 15: Caf&eacute; la Iguana &ndash; Pembroke Pines &ndash; La Florida<\/p>\n<p style=\"text-align: justify;\">Domingo 16: Rancho Las Palmas &ndash; Tampa<\/p>\n<p style=\"text-align: justify;\">Domingo 16: Salsa Latina &#8211; Orlando &#8211; Florida<\/p>\n<p style=\"text-align: justify;\">Sin duda alguna, Jorge Celed&oacute;n, el &Iacute;dolo Mundial del Vallenato, sigue llevando este lindo folclor a los mejores escenarios del mundo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ALFONSO CASTRO<\/strong><\/p>\n<p><strong>Manager General<\/strong><\/p>\n<p><strong>Cel: 3153363512<\/strong><\/p>\n<p><strong>3002130432<\/strong><\/p>\n<p><strong><a href=\"mailto:manager@jorgeceledonoficial.com\">manager@jorgeceledonoficial.com<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>JUAN CARLOS TRAVECEDO<\/strong><\/p>\n<p><strong>Director de Proyectos<\/strong><\/p>\n<p><strong>3145415466<\/strong><\/p>\n<p><strong>Correo: <a href=\"mailto:Juancarlostravecedo@gmail.com\">Juancarlostravecedo@gmail.com<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prensa C<\/strong><\/p>\n<p><strong>PAUL BOLA&Ntilde;O SAURITH<\/strong><\/p>\n<p><strong>Cel: 3157494904<\/strong><\/p>\n<p><strong>Correo: <a href=\"mailto:prensa@jorgeceledonoficial.com\">prensa@jorgeceledonoficial.com<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Celed&oacute;n, el &Iacute;dolo Mundial del Vallenato, inicia en la presente semana el Tour Sin Fronteras en Estados Unidos con seis espectaculares conciertos del 13 de febrero, en una jornada marat&oacute;nica donde ratificar&aacute; que es el artista vallenato de mayor convocatoria en el pa&iacute;s del norte. En estos seis conciertos por Virginia, New York, Tampa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12650"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=12650"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12650\/revisions"}],"predecessor-version":[{"id":12652,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/12650\/revisions\/12652"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/12651"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=12650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=12650"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=12650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}