{"id":14852,"date":"2014-12-11T18:26:52","date_gmt":"2014-12-11T23:26:52","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=14852"},"modified":"2014-12-11T18:26:52","modified_gmt":"2014-12-11T23:26:52","slug":"metro-concierto-historico-de-cartagena-ofrece-nuevo-descuento-del-20-por-ciento-hasta-el-17-de-dic","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/metro-concierto-historico-de-cartagena-ofrece-nuevo-descuento-del-20-por-ciento-hasta-el-17-de-dic\/","title":{"rendered":"Metro Concierto Hist\u00f3rico de Cartagena ofrece nuevo descuento del 20 por ciento hasta el 17 de dic"},"content":{"rendered":"<p>Ricardo Leyva Producciones y Bah\u00eda Producciones otorgan un nuevo descuento del 20 por ciento hasta el 17 de diciembre,\u00a0\u00a0a quienes no pudieron comprar sus boletas en la primera etapa, para vivir en el Estadio de Futbol Jaime Mor\u00f3n de Cartagena, el \u00faltimo concierto del 2014, y que adem\u00e1s trae dentro de su n\u00f3mina los artistas m\u00e1s importantes actualmente de la m\u00fasica latina en el mundo.<\/p>\n<p>El Metro Concierto Hist\u00f3rico Cartagena 2014, presenta a el compositor y cantante de pop #1 del mundo, adem\u00e1s de ser el artista latino con mayor venta de discos en la historia y due\u00f1o del primer lugar de la lista Hot Latin Songs de Billboard durante las \u00faltimas 30 semanas con su sencillo \u201cBailando\u201d y ganador del Latin Grammy 2014 a \u201cCanci\u00f3n del A\u00f1o\u201d, Enrique Iglesias, tambi\u00e9n, el cantante, y compositor estadounidense de ra\u00edces dominicanas y fen\u00f3meno de la m\u00fasica juvenil latina, ganador de 12 premios Billboard, 13 premios Lo Nuestro y 17 Premios Juventud y nominado al Grammy Latino 2014, Prince Royce, acompa\u00f1ados del jefe del reggueton, el cantante, compositor y productor urbano, Daddy Yankee.<\/p>\n<p>Junto a estas grandes estrellas del pop, la bachata y la m\u00fasica urbana, estar\u00e1 en el Estadio Jaime Moron de Cartagena el pr\u00f3ximo Domingo 28 de Diciembre un gran bolerista, sonero y catalogado como el caballero de la salsa, Gilberto Santarosa, quien pondr\u00e1 a bailar y gozar con todos sus \u00e9xitos a los asistentes al Metro Concierto Historico 2014.<\/p>\n<p>A las 11:30 de la noche llega una leyenda viva de la salsa, el trombonista, productor, activista social y 11 veces nominado al Grammy Latino Willie Col\u00f3n\u00a0llenando de mucho sabor, tumbao y guaganco el Jaime Mor\u00f3n.<\/p>\n<p>La cuota colombiana en el Metro Concierto Hist\u00f3rico 2014 ser\u00e1, el tres veces ganador del Grammy Latino y uno de los artistas m\u00e1s importantes de Latinoam\u00e9rica Fonseca, quien con su inmensurable talento, su mezcla\u00a0 de pop, ritmos folcl\u00f3ricos colombianos y m\u00e1s de un mill\u00f3n de discos vendidos en toda su carrera lo convierten en uno de los artistas latinos m\u00e1s importantes en la industria musical latinoamericana. Y para cerrar con broche de oro y despedir con una inolvidable parranda vallenata el 2014, a las 2:30am girar\u00e1 por \u00faltima vez el escenario del Estadio Jaime Mor\u00f3n para recibir al gran Mart\u00edn El\u00edas que con sus \u00e9xitos extender\u00e1 la rumba del Metro Concierto Hist\u00f3rico hasta el amanecer<\/p>\n<p>Ya todo est\u00e1 listo para el concierto que despedir\u00e1 a lo grande el 2014, pues se necesitan 9 hoteles, 7 angares privados, 30 camionetas, 6 aviones privados, 6 d\u00edas de montaje, 1500 personas integrando el equipo de producci\u00f3n, 15000 polic\u00edas, 3000 operadores log\u00edsticos, 20 ingenieros de sonido, 400 luces rob\u00f3ticas y 60 personas aproximadamente\u00a0 componen el staff de cada artista pues todos; Enrique Iglesias, Prince Royce, Fonseca, Daddy Yankee, Gilberto Santa Rosa, Willie Colon Y Martin Elias, presentar\u00e1n su show con banda en vivo en una tarima giratoria que incluye doble sistema de escenario para que la m\u00fasica no pare, ofreciendo un show sin precedentes que pondr\u00e1 a vibrar a los m\u00e1s de 20.000 espectadores que se esperan el pr\u00f3ximo domingo 28 de Diciembre en el Estadio Jaime Mor\u00f3n.<\/p>\n<p>Quienes no quieran perderse el concierto m\u00e1s grande e importante en la historia de Cartagena, para despedir el 2014 por todo lo alto, pueden adquirir sus entradas en <a href=\"http:\/\/www.tuboleta.com\">www.tuboleta.com<\/a> y desde un celular en el #593 con el 20% de descuento hasta el 17 de Diciembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo Leyva Producciones y Bah\u00eda Producciones otorgan un nuevo descuento del 20 por ciento hasta el 17 de diciembre,\u00a0\u00a0a quienes no pudieron comprar sus boletas en la primera etapa, para vivir en el Estadio de Futbol Jaime Mor\u00f3n de Cartagena, el \u00faltimo concierto del 2014, y que adem\u00e1s trae dentro de su n\u00f3mina los artistas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/14852"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=14852"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/14852\/revisions"}],"predecessor-version":[{"id":14854,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/14852\/revisions\/14854"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/14853"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=14852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=14852"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=14852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}