{"id":1803,"date":"2011-01-06T13:11:16","date_gmt":"2011-01-06T13:11:16","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=1803"},"modified":"2011-01-06T13:11:16","modified_gmt":"2011-01-06T13:11:16","slug":"silvio-brito-y-nemer-tetay-con-baterias-recargadas-para-el-2011","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/silvio-brito-y-nemer-tetay-con-baterias-recargadas-para-el-2011\/","title":{"rendered":"Silvio Brito y Nemer Tetay, con bater\u00edas recargadas para el 2011"},"content":{"rendered":"<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"margin: 0cm 0cm 16.2pt; background: white;\"><img decoding=\"async\" src=\"http:\/\/intervallenato.com\/inicio\/..\/web\/images\/stories\/stories\/silviobrito2090.jpg\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\">Silvio Brito &amp; Nemer Tetay comenzaron su actividad musical por Cartagena, donde cerraron el 2010 y a petici\u00f3n de sus&nbsp;seguidores regresaron a&nbsp;&#8216;La Heroica&#8217; con las bater\u00edas recargadas y la f\u00e9 en nuevos logros para cumplir con la ardua tarea del 2011.<\/p>\n<div class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\">El 2010 un a\u00f1o lleno de gloria, buenos acontecimientos, como la salida al mercado de \u201cOtra dimensi\u00f3n del Vallenato\u201d, nuestra \u00faltima Producci\u00f3n Discogr\u00e1fica; en donde&nbsp; logramos obtener un \u00e9xito a nivel nacional con la canci\u00f3n No mires atr\u00e1s, la cual se paseo por todo el territorio colombiano sonando en diferentes estaciones radiales. Entonces consideramos que fu\u00e9 un a\u00f1o victorioso para la agrupaci\u00f3n, nuestros seguidores y nuestra m\u00fasica vallenata.<\/div>\n<div class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\">Es por eso que en el comienzo del nuevo a\u00f1o, se nota el reflejo de un gran esfuerzo, una verdadera lucha por conseguir un mejor posicionamiento musical que se merecen Silvio Brito &amp; Nemer Tetay; y en donde los artistas estar\u00e1n obligados a dar grandes saltos musicales.<\/div>\n<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\"><strong>GIRA MUSICAL<\/strong><\/p>\n<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\">Jueves 6 de enero: Evento Social Privado &#8211; Cartagena.<\/p>\n<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\">Viernes 7 de enero: Disponible.<\/p>\n<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\">S\u00e1bado 8 de enero: Plaza Principal de Puerto Nare (Antioquia)<\/p>\n<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: justify; margin: 0cm 0cm 16.2pt; background: white;\">Domingo 9 de enero: Coliseo de Ferias y Exposiciones Freddy Naizaque &#8211; Jenesano (Boyac\u00e1).&nbsp;<\/p>\n<p class=\"yiv660704962yiv1636709001MsoNormal\" style=\"margin: 0cm 0cm 0pt;\"><strong>Cordialmente,<\/strong><\/p>\n<p align=\"center\" class=\"yiv660704962yiv1636709001MsoNormal\" style=\"text-align: center; margin: 0cm 0cm 0pt;\"><strong>&nbsp;<\/strong><\/p>\n<p class=\"yiv660704962yiv1636709001ecxmsonormal\" style=\"margin: 0cm 0cm 16.2pt; background: white;\"><strong>Manuel Polo<\/strong><br \/><strong>Manager<\/strong><br \/><strong>Cels. 310 612 1200<\/strong><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Silvio Brito &amp; Nemer Tetay comenzaron su actividad musical por Cartagena, donde cerraron el 2010 y a petici\u00f3n de sus&nbsp;seguidores regresaron a&nbsp;&#8216;La Heroica&#8217; con las bater\u00edas recargadas y la f\u00e9 en nuevos logros para cumplir con la ardua tarea del 2011. El 2010 un a\u00f1o lleno de gloria, buenos acontecimientos, como la salida al mercado [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/1803"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=1803"}],"version-history":[{"count":0,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/1803\/revisions"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=1803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=1803"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=1803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}