{"id":22970,"date":"2019-05-16T11:34:54","date_gmt":"2019-05-16T16:34:54","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=22970"},"modified":"2019-05-16T09:37:46","modified_gmt":"2019-05-16T14:37:46","slug":"el-festival-mar-de-acordeones-entregara-20-millones-de-pesos-para-los-ganadores-profesionales","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/el-festival-mar-de-acordeones-entregara-20-millones-de-pesos-para-los-ganadores-profesionales\/","title":{"rendered":"El Festival Mar de Acordeones entregar\u00e1 20 millones de pesos para los ganadores profesionales"},"content":{"rendered":"<p><span style=\"font-weight: 300;\">La premiaci\u00f3n del Festival Mar de Acordeones est\u00e1 garantizada y los ganadores de Acorde\u00f3n Profesional recibir\u00e1n 20 millones de pesos, anunci\u00f3 su directiva.<\/span><\/p>\n<p>El Festival Mar de Acordeones, que se realizar\u00e1 en Santa Marta del 30 de mayo al 2 de junio, entregar\u00e1 al primer puesto de Acorde\u00f3n Profesional 10 millones de pesos; para el segundo 6 y el tercero 4 millones de pesos.<\/p>\n<p>Hoy se llevar\u00e1 acabo el lanzamiento del Festival Mar de Acordeones en La Primera Restaurante Bar en Santa Marta a partir de las 4:30 de la tarde con presencia de la artista Karen Lizarazo.<\/p>\n<p>Las inscripciones est\u00e1n abiertas hasta el viernes 20 de mayo. Los interesados en participar en el Festival pueden inscribirse en la p\u00e1gina oficial: www.FestivalMardeAcordeones.com.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La premiaci\u00f3n del Festival Mar de Acordeones est\u00e1 garantizada y los ganadores de Acorde\u00f3n Profesional recibir\u00e1n 20 millones de pesos, anunci\u00f3 su directiva. El Festival Mar de Acordeones, que se realizar\u00e1 en Santa Marta del 30 de mayo al 2 de junio, entregar\u00e1 al primer puesto de Acorde\u00f3n Profesional 10 millones de pesos; para el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/22970"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=22970"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/22970\/revisions"}],"predecessor-version":[{"id":22971,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/22970\/revisions\/22971"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/22972"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=22970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=22970"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=22970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}