{"id":22994,"date":"2019-05-20T10:32:37","date_gmt":"2019-05-20T15:32:37","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=22994"},"modified":"2019-05-20T09:35:00","modified_gmt":"2019-05-20T14:35:00","slug":"orlando-linan-oficializa-harold-becerra-como-su-nuevo-manager-artistico","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/orlando-linan-oficializa-harold-becerra-como-su-nuevo-manager-artistico\/","title":{"rendered":"Orlando Li\u00f1\u00e1n oficializa Harold Becerra, como su nuevo manager art\u00edstico"},"content":{"rendered":"<p>Luego de dos meses de trabajo y resultados positivos, el artista Orlando Li\u00f1\u00e1n oficializa al ingeniero industrial, Harold Becerra como su nuevo manager art\u00edstico emprendiendo nuevos retos en su carrera profesional.<\/p>\n<p>Harol Becerra, es muy conocido en el mundo vallenato, tiene excelentes relaciones, conoce el tema y cuenta con una experiencia de 15 a\u00f1os, de los cuales 10 los trabaj\u00f3 al lado del gran Mart\u00edn El\u00edas (qepd), logrando su posicionamiento y proyecci\u00f3n.<\/p>\n<p>Ahora, Orlando Li\u00f1\u00e1n y su agrupaci\u00f3n al lado del acordeonero Mirito Castro, emprenden grandes retos con Harold Becerra, quienes avanzan a buen ritmo la grabaci\u00f3n de su nuevo \u00e1lbum en Valledupar.<\/p>\n<p>Por otra parte, Orlando Li\u00f1\u00e1n y Mirito Castro, se lucieron con sus dos presentaciones el pasado fin de semana. La primera fue el s\u00e1bado 17 de mayo en el Club Campestre de Valledupar y ayer domingo, en Pasca \u2013 Cundinamarca, donde los Orlandistas disfrutaron de sus conciertos.<\/p>\n<p>&nbsp;<\/p>\n<p>HAROLD BECERRA<\/p>\n<p>Instagram @haroldbecerra<\/p>\n<p>Celular y WhatsApp : 3505341918<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de dos meses de trabajo y resultados positivos, el artista Orlando Li\u00f1\u00e1n oficializa al ingeniero industrial, Harold Becerra como su nuevo manager art\u00edstico emprendiendo nuevos retos en su carrera profesional. Harol Becerra, es muy conocido en el mundo vallenato, tiene excelentes relaciones, conoce el tema y cuenta con una experiencia de 15 a\u00f1os, de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/22994"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=22994"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/22994\/revisions"}],"predecessor-version":[{"id":22996,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/22994\/revisions\/22996"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/22995"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=22994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=22994"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=22994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}