{"id":23721,"date":"2019-08-05T13:05:05","date_gmt":"2019-08-05T18:05:05","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=23721"},"modified":"2019-08-05T08:13:33","modified_gmt":"2019-08-05T13:13:33","slug":"uribia-guajira-confirma-que-es-territorio-kvrass","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/uribia-guajira-confirma-que-es-territorio-kvrass\/","title":{"rendered":"Uribia \u2013 Guajira, confirma que es territorio Kvrass"},"content":{"rendered":"<p><span style=\"font-weight: 300;\">En el coraz\u00f3n de la Guajira est\u00e1 el Grupo Kvrass, y as\u00ed qued\u00f3 confirmado el pasado fin de semana durante su presentaci\u00f3n en el municipio de Uribia.<\/span><\/p>\n<p>Los guajiros llenaron la plaza para ver en sensacional concierto del Grupo Kvrass, que sigue impactando con su \u00e9xito \u2018Cuatro tragos\u2019.<\/p>\n<p>Los artistas de Kvrass, entregaron una oraci\u00f3n y agradecieron a Dios por tantas bendiciones y por la gente maravillosa de Uribia, que los aplaudi\u00f3 durante el concierto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el coraz\u00f3n de la Guajira est\u00e1 el Grupo Kvrass, y as\u00ed qued\u00f3 confirmado el pasado fin de semana durante su presentaci\u00f3n en el municipio de Uribia. Los guajiros llenaron la plaza para ver en sensacional concierto del Grupo Kvrass, que sigue impactando con su \u00e9xito \u2018Cuatro tragos\u2019. Los artistas de Kvrass, entregaron una oraci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/23721"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=23721"}],"version-history":[{"count":2,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/23721\/revisions"}],"predecessor-version":[{"id":23723,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/23721\/revisions\/23723"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/23383"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=23721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=23721"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=23721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}