{"id":27856,"date":"2020-12-18T16:18:34","date_gmt":"2020-12-18T21:18:34","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=27856"},"modified":"2020-12-18T16:18:34","modified_gmt":"2020-12-18T21:18:34","slug":"estos-son-los-conciertos-presenciales-y-virtuales-del-vallenatos-en-el-fin-de-semana","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/estos-son-los-conciertos-presenciales-y-virtuales-del-vallenatos-en-el-fin-de-semana\/","title":{"rendered":"Estos son los conciertos presenciales y virtuales del vallenatos en el fin de semana"},"content":{"rendered":"<p><span style=\"font-weight: 300;\">El g\u00e9nero vallenato sigue a la vanguardia en los conciertos virtuales y presenciales en el presente semana.<\/span><\/p>\n<p>Estos son los conciertos confirmados:<\/p>\n<p>Viernes 18 de diciembre: Super conciertos Afinia: con Iv\u00e1n Villaz\u00f3n &#8211; Elder Day\u00e1n y Rolando Ochoa &#8211; Mr. Black y Papo Man. Plataforma: Afinia.com<\/p>\n<p>Viernes 18 de diciembre: Poncho Zuleta y Ana del Castillo &#8211; plataforma Comfacesar.com.<\/p>\n<p>Viernes 18 de diciembre: Gussi &#8211; Plataforma- Caja de M\u00fasica Live.<\/p>\n<p>Viernes 18 de diciembre: concierto presencial y virtual Fusi\u00f3n al Aire: Elder Day\u00e1n &amp; Rolando Ochoa &#8211; Jessi Uribe &#8211; Paola Jara &#8211; parqueadero Centro Comercial Green Hill en Tunja &#8211; Bogot\u00e1. Plataforma- Passline.com.<\/p>\n<p>Viernes 18 de diciembre: Nuestra Parranda &#8211; Alvaro Meza &#8211; Ciro Meza y Fernando Meneses &#8211; 8 pm &#8211; Redes sociales de los artistas.<\/p>\n<p>S\u00e1bado 19 de diciembre: 25 a\u00f1os de vida art\u00edstica de Nelson Vel\u00e1squez &#8211; invitados especiales: Alex Manga &#8211; Miguel Morales &#8211; Jean Carlos Centeno &#8211; Danny Vel\u00e1squez- Luis Mateus &#8211; Jorge Pabuena &#8211; Hebert Vargas &#8211; Daniel Calder\u00f3n en el Aeroparque Juan Pablo II en Medell\u00edn.<\/p>\n<p>S\u00e1bado 19 de diciembre: concierto Vallenato y Caribe con: el Rey Vallenato Fernando Rangel, La Regi\u00f3n, Orlando Acosta, Mait\u00e9 Montero, El Puma del Vallenato &#8211; Plataforma: Vive Live Tv.<\/p>\n<p>S\u00e1bado 19 de diciembre: Concierto virtual Pal Pueblo con Los Pelaos de Jader Dur\u00e1n &#8211; invitados especiales el rey vallenato Nacer Dur\u00e1n y el compositor Luis Dur\u00e1n Escorcia. Plataforma Passline.com &#8211; 8 pm<\/p>\n<p>Lunes 21 de diciembre: Kandy Maku en la celebraci\u00f3n de los 53 a\u00f1os de la creaci\u00f3n del Cesar &#8211; Valledupar<\/p>\n<p>Mi\u00e9rcoles 23 de diciembre: Club Social Valledupar presenta: Diego Daza &#8211; Carlos Rueda; Tian Villalobos, Sergio Moya y Julio de la Ossa. Plataforma: T\u00faboleta.com &#8211; 8 pm.<\/p>\n<p>*Servicio Informativo de Intervallenato.com*<br \/>\n*Paul Bola\u00f1o Saurith*<br \/>\n*Cel.: 3157494904*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El g\u00e9nero vallenato sigue a la vanguardia en los conciertos virtuales y presenciales en el presente semana. Estos son los conciertos confirmados: Viernes 18 de diciembre: Super conciertos Afinia: con Iv\u00e1n Villaz\u00f3n &#8211; Elder Day\u00e1n y Rolando Ochoa &#8211; Mr. Black y Papo Man. Plataforma: Afinia.com Viernes 18 de diciembre: Poncho Zuleta y Ana del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/27856"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=27856"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/27856\/revisions"}],"predecessor-version":[{"id":27859,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/27856\/revisions\/27859"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/27858"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=27856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=27856"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=27856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}