{"id":27894,"date":"2020-12-29T14:38:29","date_gmt":"2020-12-29T19:38:29","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=27894"},"modified":"2020-12-29T14:38:29","modified_gmt":"2020-12-29T19:38:29","slug":"la-red-mundial-del-vallenato-presenta-lo-mejor-de-la-musica-vallenata-2020","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/la-red-mundial-del-vallenato-presenta-lo-mejor-de-la-musica-vallenata-2020\/","title":{"rendered":"La red mundial del vallenato, presenta lo mejor de la m\u00fasica vallenata 2020"},"content":{"rendered":"<p>La Red Mundial del Vallenato entrega \u2018Lo Mejor del Vallenato 2020\u2019 en diferentes categor\u00edas consolidando los hechos m\u00e1s destacados en el presente a\u00f1o en pa\u00edses como Estados Unidos, M\u00e9xico, Panam\u00e1, Ecuador, Venezuela, Aruba, Argentina, Paraguay y Espa\u00f1a.<\/p>\n<p>&nbsp;<\/p>\n<p>Hace diez a\u00f1os fue creada La Red Mundial del Vallenato por Paul Bola\u00f1o Saurith, periodista y director del portal Intervallenato.com, quien, desde Valledupar, suministra diariamente las noticias de los artistas y acontecimientos del folclor a los medios de comunicaciones de esos pa\u00edses.<\/p>\n<p>&nbsp;<\/p>\n<p>La Red Mundial del Vallenato est\u00e1 integrada por m\u00e1s de 50 comunicadores de todo el mundo y en esta versi\u00f3n, en \u2018Lo Mejor del Vallenato 2020\u2019, participaron con su votaci\u00f3n los siguientes profesionales de la radio y televisi\u00f3n:<\/p>\n<p>&nbsp;<\/p>\n<p>Jorge Socarr\u00e1s del programa Encuentro Vallenato en Miami (Estados Unidos)<\/p>\n<p>&nbsp;<\/p>\n<p>Johnny Carrasquilla, director Tropical Music TV y Vallenato Internacional Radio y TV\u2013 Miami (Estados Unidos)<\/p>\n<p>&nbsp;<\/p>\n<p>Adri\u00e1n Sarmiento de La Parranda Vallenata de Am\u00e9rica Stereo en Quito (Ecuador)<\/p>\n<p>&nbsp;<\/p>\n<p>Marlon Rey de La Gozadera en La Nueva Latina 92.3 en Aruba<\/p>\n<p>&nbsp;<\/p>\n<p>Tony Pastrana del Show de Tony Pastrana de Candela Pura 91.9 Fm del Circuito FM Center<\/p>\n<p>&nbsp;<\/p>\n<p>Jorge Rivera de Fiesta Vallenata en Latinos FM en Barcelona (Espa\u00f1a)<\/p>\n<p>&nbsp;<\/p>\n<p>Gustavo Tena, director de Vallenatoalcien.com \u2013 Valencia (Espa\u00f1a)<\/p>\n<p>&nbsp;<\/p>\n<p>L\u00e1zaro Cervantes de Colombia con amor por Libertad 102.1 FM en Monterrey \u2013\u2013 Grupo Radio Nuevo Le\u00f3n (M\u00e9xico)<\/p>\n<p>&nbsp;<\/p>\n<p>Gustavo Mareco \u2013 El Especial del Vallenato \u2013 FM 97.1 Espa\u00f1a \u2013 Resistencia (Argentina)<\/p>\n<p>&nbsp;<\/p>\n<p>Ulises Alvarado de XEN 1420 AM \u2013 Antolog\u00eda Vallenata de Monterrey (M\u00e9xico)<\/p>\n<p>&nbsp;<\/p>\n<p>Mimo Villaz\u00f3n y Mario Lara, de Mundo Vallenato de Radio 13 La M\u00e1s Vallenata \u2013 Monterr<\/p>\n<p>&nbsp;<\/p>\n<p>Vic Leija \u2018El Heavy del Vallenato\u2019 &#8211; programa Vallenateando \u2013 Facebook Cabina 57 \u2013 Monterrey &#8211; M\u00e9xico<\/p>\n<p>&nbsp;<\/p>\n<p>V\u00edctor \u2018El Nene\u2019 Bomba \u2013 La Parranda Vallenata emisora La Tipik \u2013 Ciudad de Panam\u00e1 (Panam\u00e1)<\/p>\n<p>&nbsp;<\/p>\n<p>Dahiana Ortiz Servin \u2013 La Parranda Vallenata \u2013 101.3 FM \u2013 La Voz Latina \u2013 Barracas \u2013 Argentina<\/p>\n<p>&nbsp;<\/p>\n<p>LO MEJOR DEL VALLENATO<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Personaje del a\u00f1o: Romualdo Brito<\/li>\n<\/ol>\n<p>El maestro Romualdo Brito dej\u00f3 un gran legado musical con m\u00e1s de 1.500 canciones grabadas y un ba\u00fal de temas in\u00e9ditos. Fue un compositor vers\u00e1til y muy polifac\u00e9tico que le hizo canciones al amor, a su pueblo, a las costumbres, mostrando su picard\u00eda en muchos temas.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"2\">\n<li>Mejor artista: Jorge Celed\u00f3n<\/li>\n<\/ol>\n<p>Ganador del Grammy Latino en el a\u00f1o 2020 con el \u00e1lbum \u2018Sigo cantando al amor\u2019, es el \u00fanico artista del g\u00e9nero vallenato que lleva 5 gram\u00f3fonos y est\u00e1 nominado al Grammy Americano en la categor\u00eda Tropical con la misma producci\u00f3n. Jorge Celed\u00f3n, el \u00cddolo Mundial del Vallenato, sigue siendo un gran embajador de Colombia ante el mundo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"3\">\n<li>Mejor concierto: Silvestre Dangond<\/li>\n<\/ol>\n<p>El concierto virtual de Silvestre Dangond, en el Pueblito Vallenato, a orillas del r\u00edo Guatapur\u00ed, con el encanto de la Sirena en Valledupar, fue un verdadero acierto y cumpli\u00f3 con todas las expectativas en mercadeo. Fueron 5 horas de concierto que unieron a muchas familias en Colombia y el mundo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"4\">\n<li>Mejor Compositor: Jorge Valbuena<\/li>\n<\/ol>\n<p>Jorge Valbuena se mantuvo vigente y entre sus recientes canciones grabadas figuran: Razones para odiarte con Peter Manjarrez; Amor al instante \u2013 Beto Zabaleta y Jorge Valbuena; So\u00f1ando contigo &#8211; Miguel morales; A pisar con cuidadito, La Gente de Diomedez y El regalito de mi Dios \u2013 Jorge Valbuena; Lo material se recupera \u2013 Luifer Cuello.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"6\">\n<li>Manager del a\u00f1o: Manuel Polo &#8211; manager de Alex Manga<\/li>\n<\/ol>\n<p>La visi\u00f3n empresarial de Manuel Polo, siempre va a encaminada a mantener activo a su artista y en este sentido, Alex Manga, ha sido un cantante que se ha reactivado en medio de esta pandemia cumpliendo compromisos en Colombia, Estados Unidos y otros pa\u00edses. Su organizaci\u00f3n, seriedad y cumplimiento hacen que Manuel Polo sea el manager del a\u00f1o 2020.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"7\">\n<li>Manager Revelaci\u00f3n: Sachy G\u00f3mez &#8211; de Hebert Vargas<\/li>\n<\/ol>\n<p>Santiago \u2018Sachy\u2019 G\u00f3mez, es un joven manager de Medell\u00edn que ha posicionado en los primeros lugares de preferencia a Hebert Vargas, logrando importantes presentaciones en Colombia y el exterior. Su seriedad, organizaci\u00f3n y disciplina son m\u00e9ritos para ser el Manager Revelaci\u00f3n 2020 en La Red Mundial del Vallenato.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"8\">\n<li>Vida y obra: Joel Luna<\/li>\n<\/ol>\n<p>Joel Luna, quien muri\u00f3 recientemente, fue el pionero de la difusi\u00f3n de la m\u00fasica colombiana en Monterrey (M\u00e9xico) y especialmente, la vallenata. Director de la XEH 1420AM \u2013 Antolog\u00eda Vallenata, hace 42 a\u00f1os sembr\u00f3 la semilla que hoy tiene a esta capital con m\u00e1s de 20 programas vallenatos, escuelas de m\u00fasica y conciertos multitudinarios con artistas del g\u00e9nero.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"9\">\n<li>Mejor canci\u00f3n: Las locuras m\u00edas &#8211; Omar Geles<\/li>\n<\/ol>\n<p>\u2018Las locuras m\u00edas\u2019, es una canci\u00f3n rom\u00e1ntica de la autor\u00eda de Omar Geles, grabada por Silvestre Dangond y que le da t\u00edtulo a su reciente producci\u00f3n musical. El tema ya supera los 31 millones de reproducciones con su video oficial en la plataforma de Youtube. Un verdadero \u00e9xito.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"10\">\n<li>Mejor cantante femenina: Karen Lizarazo<\/li>\n<\/ol>\n<p>Karen Lizarazo, ha mostrado su profesionalismo, organizaci\u00f3n y disciplina, con su \u00e1lbum \u2018Voz de Mujer\u2019, fue nominada por primera vez al Grammy Latino 2020, en la categor\u00eda Vallenato Cumbia. Tambi\u00e9n figura entre las 50 personas emprendedoras de Colombia escogidas por la revista Forbes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"12\">\n<li>Artista de Mayor Proyecci\u00f3n: Rafa P\u00e9rez<\/li>\n<\/ol>\n<p>Rafa P\u00e9rez y La Evoluci\u00f3n, son muestra de perseverancia, liderazgo y organizaci\u00f3n. Ha sabido evolucionar como solista y ha sido exitoso en sus iniciativas en los conciertos con los compositores. Es visionario, emprendedor y tiene mucho futuro en la m\u00fasica vallenata. Traspasar\u00e1 fronteras.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"13\">\n<li>Artista internacional: Alex Manga<\/li>\n<\/ol>\n<p>Alex Manga, es un artista que sigue en los grandes escenarios de Colombia y el mundo. Este a\u00f1o logr\u00f3 actuar en Estados Unidos y su agenda contemplaba presentaciones en Venezuela, Chile, Argentina, Ecuador y Europa. Su m\u00fasica sigue traspasando fronteras y es un artista muy solicitado en el exterior.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"14\">\n<li>CD del a\u00f1o: \u2018Las locuras m\u00edas\u2019<\/li>\n<\/ol>\n<p>\u2018Las locuras m\u00edas\u2019 con Silvestre Dangond, es el CD del a\u00f1o 2020. El \u00e1lbum contiene 17 canciones y han sido de total impacto con los temas \u2018Las locuras m\u00edas\u2019, \u2018Tengo un Dios\u2019, \u2018Me tiene pechich\u00f3n\u2019, y otros que han logrado en tiempo r\u00e9cord primeros lugares. Es un \u00e1lbum muy escuchado y solicitado.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"15\">\n<li>Feat del a\u00f1o: Iv\u00e1n Villaz\u00f3n &amp; Iv\u00e1n Ovalle &#8211; Una loca humanidad<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Iv\u00e1n Villaz\u00f3n e Iv\u00e1n Ovalle, lanzaron la canci\u00f3n \u2018Una loca humanidad\u2019, con un mensaje claro que invita a la reflexi\u00f3n por esas rivalidades que tiene el hombre y que est\u00e1n acabando el mundo. El Feat, cuenta con un excelente video y la participaci\u00f3n del acordeonero Manuel Juli\u00e1n Mart\u00ednez. \u2018Una loca humidad\u2019 es el Feat del a\u00f1o 2020 en La Red Mundial del Vallenato.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"16\">\n<li>Artista revelaci\u00f3n del vallenato: Jorge Jerez<\/li>\n<\/ol>\n<p>Jorge Jerez, es un joven cantante vallenato que se dio a conocer en un reality de televisi\u00f3n con el \u2018YomellamoMart\u00ednElias\u2019. Actualmente con la raz\u00f3n social de su propio nombre, inici\u00f3 su nueva faceta y logr\u00f3 impactar con la nueva versi\u00f3n de la canci\u00f3n \u2018Vela ve\u2019 y con su repertorio, ha tenido un gran trabajo, formalizando uni\u00f3n con el acordeonero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Red Mundial del Vallenato entrega \u2018Lo Mejor del Vallenato 2020\u2019 en diferentes categor\u00edas consolidando los hechos m\u00e1s destacados en el presente a\u00f1o en pa\u00edses como Estados Unidos, M\u00e9xico, Panam\u00e1, Ecuador, Venezuela, Aruba, Argentina, Paraguay y Espa\u00f1a. &nbsp; Hace diez a\u00f1os fue creada La Red Mundial del Vallenato por Paul Bola\u00f1o Saurith, periodista y director [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26726,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/27894"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=27894"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/27894\/revisions"}],"predecessor-version":[{"id":27895,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/27894\/revisions\/27895"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/26726"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=27894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=27894"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=27894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}