{"id":28772,"date":"2021-04-15T08:52:15","date_gmt":"2021-04-15T13:52:15","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=28772"},"modified":"2021-04-15T08:52:15","modified_gmt":"2021-04-15T13:52:15","slug":"ivan-villazon-estrena-hoy-los-4-aires-con-la-reina-del-festival-vallenato-2020-yeimi-arrieta","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/ivan-villazon-estrena-hoy-los-4-aires-con-la-reina-del-festival-vallenato-2020-yeimi-arrieta\/","title":{"rendered":"Iv\u00e1n Villaz\u00f3n estrena hoy los 4 aires con la reina del Festival Vallenato 2020, Yeimi Arrieta"},"content":{"rendered":"<p class=\"p1\">En un verdadero gesto se apoyo y respaldo a las mujeres de nuestro folclor, Iv\u00e1n Villaz\u00f3n presenta hoy los 4 aires con la reina de la categor\u00eda Acordeonera Mayor del Festival Vallenato 2020, Yeimi Arrieta.<\/p>\n<p class=\"p1\"><span class=\"s1\">Las canciones grabadas fueron las siguientes:<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">1. Mi estilo \u2013 paseo &#8211; Nafer Dur\u00e1n <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">2. Palomita mora \u2013 merengue &#8211; Abel Antonio Villa <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">3. El testamentico &#8211; son &#8211; Crisp\u00edn E Villaz\u00f3n <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">4. La puya de las mujeres \u2013 puya \u2013 Isaac Calvo. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El lanzamiento de los 4 aires se hace hoy para sentir esa grata recordaci\u00f3n del Festival Vallenato que tradicionalmente se celebra a finales del mes abril pero que este a\u00f1o ser\u00e1 en la primera quincena del mes de octubre por los efectos de la pandemia. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El Cantor de Cantores, Iv\u00e1n Villaz\u00f3n, le da un gran espaldarazo a las mujeres que hoy muestran su talento en la m\u00fasica vallenata y con la reina Yeimi Arrieta, destaca su talento y creatividad con el acorde\u00f3n.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un verdadero gesto se apoyo y respaldo a las mujeres de nuestro folclor, Iv\u00e1n Villaz\u00f3n presenta hoy los 4 aires con la reina de la categor\u00eda Acordeonera Mayor del Festival Vallenato 2020, Yeimi Arrieta. Las canciones grabadas fueron las siguientes: 1. Mi estilo \u2013 paseo &#8211; Nafer Dur\u00e1n 2. Palomita mora \u2013 merengue &#8211; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28763,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/28772"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=28772"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/28772\/revisions"}],"predecessor-version":[{"id":28773,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/28772\/revisions\/28773"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/28763"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=28772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=28772"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=28772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}