{"id":32425,"date":"2022-08-08T13:07:08","date_gmt":"2022-08-08T18:07:08","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=32425"},"modified":"2022-08-08T13:07:08","modified_gmt":"2022-08-08T18:07:08","slug":"bucaramanga-vivio-la-mejor-parranda-vallenata-con-ivan-villazon","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/bucaramanga-vivio-la-mejor-parranda-vallenata-con-ivan-villazon\/","title":{"rendered":"Bucaramanga vivi\u00f3 la mejor parranda vallenata con Iv\u00e1n Villaz\u00f3n"},"content":{"rendered":"<p class=\"p1\">Bucaramanga &#8216;La Ciudad Bonita vivi\u00f3 la mejor parranda vallenata con El Cantor de Cantores, Iv\u00e1n Villaz\u00f3n quien llen\u00f3 el restaurante bar &#8216;Mulatas&#8217; el pasado fin de semana.<\/p>\n<p class=\"p1\"><span class=\"s1\">Los santandereanos disfrutaron durante dos horas el majestuoso concierto de Iv\u00e1n Villaz\u00f3n y &#8216;El Tuto&#8217; L\u00f3pez, quienes entregaron esos grandes \u00e9xitos para complacer a sus seguidores.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Los artistas interpretaron temas como: Me quedo con tus besos, No me pidas que te olvides, Mi alma en pleno, El ni\u00f1o bonito y El Pechiche, entre otros.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Luego de su fant\u00e1stica presentaci\u00f3n en Bucaramanga, la agrupaci\u00f3n de Iv\u00e1n Villaz\u00f3n anim\u00f3 un cumplea\u00f1os en Cartagena en el piso 32 con el marco iluminado de las edificaciones y al frente la inmensidad del mar Caribe.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bucaramanga &#8216;La Ciudad Bonita vivi\u00f3 la mejor parranda vallenata con El Cantor de Cantores, Iv\u00e1n Villaz\u00f3n quien llen\u00f3 el restaurante bar &#8216;Mulatas&#8217; el pasado fin de semana. Los santandereanos disfrutaron durante dos horas el majestuoso concierto de Iv\u00e1n Villaz\u00f3n y &#8216;El Tuto&#8217; L\u00f3pez, quienes entregaron esos grandes \u00e9xitos para complacer a sus seguidores. Los artistas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32425"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=32425"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32425\/revisions"}],"predecessor-version":[{"id":32427,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32425\/revisions\/32427"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/32426"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=32425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=32425"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=32425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}