{"id":37300,"date":"2024-01-29T08:42:10","date_gmt":"2024-01-29T13:42:10","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=37300"},"modified":"2024-01-29T08:42:11","modified_gmt":"2024-01-29T13:42:11","slug":"el-mono-zabaleta-presenta-en-rueda-de-prensa-su-nuevo-album-titulado-mono","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/el-mono-zabaleta-presenta-en-rueda-de-prensa-su-nuevo-album-titulado-mono\/","title":{"rendered":"El Mono Zabaleta presenta en rueda de prensa su nuevo \u00e1lbum titulado \u2018Mono\u2019"},"content":{"rendered":"\n<p>Comenz\u00f3 la cuenta regresiva para el lanzamiento en vivo del nuevo \u00e1lbum del Mono Zabaleta, titulado \u2018Mono\u2019 este s\u00e1bado 3 de febrero en el parque de la Leyenda de Valledupar<\/p>\n\n\n\n<p>El Mono Zabaleta, presentar\u00e1 este mi\u00e9rcoles 31 de enero su nuevo \u00e1lbum \u2018Mono\u2019 en rueda de prensa en la Casa Ferrandis al norte de la ciudad a partir de las 5 pm.<\/p>\n\n\n\n<p>En este encuentro con la prensa de la regi\u00f3n el Mono Zabaleta entregar\u00e1 detalles de esta producci\u00f3n musical que contiene 18 canciones que alegran esta temporada del Carnaval del Mono, como se llama su agenda de actividades.<\/p>\n\n\n\n<p>La programaci\u00f3n Monista es la siguiente:&nbsp;<\/p>\n\n\n\n<p>Mi\u00e9rcoles 31 enero: &#8211; 5:00 PM<\/p>\n\n\n\n<p>RUEDA DE PRENSA &#8211; CASA FERRANDIS \u2013 Valledupar&nbsp;<\/p>\n\n\n\n<p>Ubicaci\u00f3n: v\u00eda a La Pedregosa al lado de la sede de Las Clarisas<\/p>\n\n\n\n<p>Jueves 1 febrero &#8211; 4:00 PM<\/p>\n\n\n\n<p>BOLETATON \u2013 repartici\u00f3n de boletas, camisetas, gorras en Valledupar<\/p>\n\n\n\n<p>Viernes 2 febrero -3:00 PM<\/p>\n\n\n\n<p>ENCUENTRO MONISTA \u2013 Parque El Viajero de Valledupar \u2013 carrera 9 con calle 12.<\/p>\n\n\n\n<p>Viernes 2 de febrero \u2013 3:00 PM<\/p>\n\n\n\n<p>GUACHERNA MONISTA \u2013 parqueadero Parque La Provincia \u2013 Valledupar<\/p>\n\n\n\n<p>S\u00e1bado 3 de febrero &#8211; 5:00 PM<\/p>\n\n\n\n<p>LANZAMIENTO en vivo del \u00e1lbum \u2018MONO\u2019 \u2013 Parque de la Leyenda \u2013 Valledupar&nbsp;<\/p>\n\n\n\n<p>En Valledupar el entusiasmo es total por la programaci\u00f3n Monista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comenz\u00f3 la cuenta regresiva para el lanzamiento en vivo del nuevo \u00e1lbum del Mono Zabaleta, titulado \u2018Mono\u2019 este s\u00e1bado 3 de febrero en el parque de la Leyenda de Valledupar El Mono Zabaleta, presentar\u00e1 este mi\u00e9rcoles 31 de enero su nuevo \u00e1lbum \u2018Mono\u2019 en rueda de prensa en la Casa Ferrandis al norte de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37301,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,55],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/37300"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=37300"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/37300\/revisions"}],"predecessor-version":[{"id":37302,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/37300\/revisions\/37302"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/37301"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=37300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=37300"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=37300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}