{"id":37330,"date":"2024-01-30T11:04:20","date_gmt":"2024-01-30T16:04:20","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=37330"},"modified":"2024-01-30T11:04:22","modified_gmt":"2024-01-30T16:04:22","slug":"el-vallero-diaz-cantara-en-el-festival-de-la-paletilla","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/el-vallero-diaz-cantara-en-el-festival-de-la-paletilla\/","title":{"rendered":"El Vallero Diaz cantar\u00e1 en el Festival de la Paletilla"},"content":{"rendered":"\n<p>El carism\u00e1tico cantante &#8216;El Vallero&#8217; Diaz cantar\u00e1 este viernes 2 de febrero en el Festival de la Paletilla en Becerril &#8211; Cesar.<\/p>\n\n\n\n<p>El Vallero Diaz llevar\u00e1 a Becerril esas canciones de su \u00e1lbum &#8216;Se pa&#8217; donde voy&#8217; donde se destacan canciones como: Amor verdadero, Que canallada, El sabroso y Linda<\/p>\n\n\n\n<p>El artista de la dinast\u00eda del inmortal Diomedes Diaz estar\u00e1 presente en el Carnaval de Barranquilla actuando en eventos privados.<\/p>\n\n\n\n<p>El Vallero Diaz vincul\u00f3 a su organizaci\u00f3n musical a su nuevo manager Antony Morales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El carism\u00e1tico cantante &#8216;El Vallero&#8217; Diaz cantar\u00e1 este viernes 2 de febrero en el Festival de la Paletilla en Becerril &#8211; Cesar. El Vallero Diaz llevar\u00e1 a Becerril esas canciones de su \u00e1lbum &#8216;Se pa&#8217; donde voy&#8217; donde se destacan canciones como: Amor verdadero, Que canallada, El sabroso y Linda El artista de la dinast\u00eda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37331,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,55],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/37330"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=37330"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/37330\/revisions"}],"predecessor-version":[{"id":37332,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/37330\/revisions\/37332"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/37331"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=37330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=37330"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=37330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}