{"id":42197,"date":"2025-09-22T17:37:12","date_gmt":"2025-09-22T22:37:12","guid":{"rendered":"https:\/\/intervallenato.com\/inicio\/?p=42197"},"modified":"2025-09-23T17:39:03","modified_gmt":"2025-09-23T22:39:03","slug":"cuadro-de-honor-del-57-festival-cuna-de-acordeones-de-villanueva-la-guajira","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/cuadro-de-honor-del-57-festival-cuna-de-acordeones-de-villanueva-la-guajira\/","title":{"rendered":"CUADRO DE HONOR DEL 57 FESTIVAL CUNA DE ACORDEONES DE VILLANUEVA \u2013 LA GUAJIRA"},"content":{"rendered":"\n<p>Aqu\u00ed est\u00e1 el cuadro de honor del 47 Festival Cuna de Acordeones de Villanueva \u2013 La Guajira<\/p>\n\n\n\n<p><strong>ACORDE\u00d3N PROFESIONAL<\/strong><\/p>\n\n\n\n<p>1. Jorge Vergel Vargas, de Oca\u00f1a \u2013 Norte de Santander<\/p>\n\n\n\n<p>2. Arismaldi Loperena \u2013 Arhuaco<\/p>\n\n\n\n<p>3. Ronal Torres \u2013 Duitama &#8211; Boyac\u00e1&nbsp;<\/p>\n\n\n\n<p><strong>ACORDE\u00d3N INFANTIL<\/strong><\/p>\n\n\n\n<p>1. Mar\u00eda Jos\u00e9 Arias P\u00e9rez \u2013 Fusagasug\u00e1 \u2013 Cundinamarca<\/p>\n\n\n\n<p>2. Nicol\u00e1s Andr\u00e9s Vega \u2013 Villanueva \u2013 La Guajira<\/p>\n\n\n\n<p>3. Aram Joen Calder\u00f3n &#8211; Barranquilla<\/p>\n\n\n\n<p><strong>ACORDEONERO JUVENIL<\/strong><\/p>\n\n\n\n<p>1. Santiago Herrera Martelo \u2013 Villanueva, La Guajira<\/p>\n\n\n\n<p>2. Emanuel Maestre \u00c1lvarez \u2013 Monter\u00eda, C\u00f3rdoba<\/p>\n\n\n\n<p>3. Sara Rhenals Escobar \u2013 Santa Marta, Magdalena<\/p>\n\n\n\n<p><strong>ACORDE\u00d3N AFICIONADO<\/strong><\/p>\n\n\n\n<p>1. Jhon Jairo Rivas \u2013 Neiva<\/p>\n\n\n\n<p>2. Laowrence Noguera \u2013 Barranquilla<\/p>\n\n\n\n<p>3. Didier Jos\u00e9 Var\u00f3n \u2013 Valledupar<\/p>\n\n\n\n<p><strong>PIQUERIA<\/strong><\/p>\n\n\n\n<p>1. Teobaldo Pe\u00f1aloza \u2013 Villanueva La Guajira&nbsp;<\/p>\n\n\n\n<p>2. Jaime Amaya \u2013 Villanueva La Guajira&nbsp;<\/p>\n\n\n\n<p>3. Jaider David Daza \u2013 San Juan del Cesar<\/p>\n\n\n\n<p><strong>CANCI\u00d3N IN\u00c9DITA<\/strong><\/p>\n\n\n\n<p>1. Ll\u00f3renla- Wilmar Bola\u00f1os &#8211; Paseo &#8211; (Villanueva)&nbsp;<\/p>\n\n\n\n<p>2. \u00bfDe qui\u00e9n es el Pintao? &#8211; Jaime Amaya &#8211; Paseo \u2013 (Villanueva)<\/p>\n\n\n\n<p>3. No sabes querer &#8211; Lisandro Sierra &#8211; Paseo &#8211; (San Juan del Cesar)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed est\u00e1 el cuadro de honor del 47 Festival Cuna de Acordeones de Villanueva \u2013 La Guajira ACORDE\u00d3N PROFESIONAL 1. Jorge Vergel Vargas, de Oca\u00f1a \u2013 Norte de Santander 2. Arismaldi Loperena \u2013 Arhuaco 3. Ronal Torres \u2013 Duitama &#8211; Boyac\u00e1&nbsp; ACORDE\u00d3N INFANTIL 1. Mar\u00eda Jos\u00e9 Arias P\u00e9rez \u2013 Fusagasug\u00e1 \u2013 Cundinamarca 2. Nicol\u00e1s Andr\u00e9s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":42198,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,55],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/42197"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=42197"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/42197\/revisions"}],"predecessor-version":[{"id":42199,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/42197\/revisions\/42199"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/42198"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=42197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=42197"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=42197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}