{"id":9799,"date":"2013-05-03T05:22:21","date_gmt":"2013-05-03T10:22:21","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=9799"},"modified":"2013-05-03T05:22:21","modified_gmt":"2013-05-03T10:22:21","slug":"carlos-vergel-y-ruben-rodriguez-preparan-el-lanzamiento-del-video-polos-opuestos","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/carlos-vergel-y-ruben-rodriguez-preparan-el-lanzamiento-del-video-polos-opuestos\/","title":{"rendered":"Carlos Vergel y Rub\u00e9n Rodr\u00edguez preparan el lanzamiento del video &#8216;Polos Opuestos&#8217;"},"content":{"rendered":"<p>Gracias al &eacute;xito que ha tenido el &aacute;lbum &ldquo;Polos opuestos&rdquo; de Carlos Vergel y Rub&eacute;n Rodr&iacute;gyez, se han ido concretando varias presentaciones en Colombia y Venezuela, donde podr&aacute;n mostrar en vivo con toda su agrupaci&oacute;n la propuesta musical con la cual han logrado sobresalir como nuevos exponentes del vallenato rom&aacute;ntico.<\/p>\n<p>Por ello ya est&aacute; en marcha la planificaci&oacute;n para el lanzamiento de &ldquo;Polos opuestos&rdquo; en la ciudad de C&uacute;cuta, donde actualmente Carlos y Rub&eacute;n gozan de amplio reconocimiento y la canci&oacute;n &ldquo;Alguna vez&rdquo; suena con mucha fuerza. Muy pronto les daremos m&aacute;s detalles acerca de la fecha y el lugar en el que realizar&aacute;n este espect&aacute;culo.<\/p>\n<p>Justamente cabe destacar como &ldquo;Alguna vez&rdquo; semana a semana sigue disparando su auge tanto en la radio, como tambi&eacute;n su video en los canales de televisi&oacute;n e internet, el posicionamiento se hace evidente al incrementarse su difusi&oacute;n y consagrando a Carlos Vergel y Rub&eacute;n Rodr&iacute;guez.<\/p>\n<p>Para retribuir todo el cari&ntilde;o que han recibido de parte de sus seguidores, CARLOS &amp; RUBEN tienen preparadas varias sorpresas en las que estar&aacute;n regalando pr&oacute;ximamente premios a trav&eacute;s de su sitio web y de las redes sociales.<\/p>\n<p>Aqu&iacute; pueden ver el video de &ldquo;Alguna vez&rdquo; desde PC o m&oacute;viles: <a href=\"http:\/\/www.youtube.com\/watch?v=nciqxHuYydA\">http:\/\/www.youtube.com\/watch?v=nciqxHuYydA<\/a><\/p>\n<p>Aqu&iacute; pueden descargar la canci&oacute;n &ldquo;Alguna vez&rdquo; desde PC o m&oacute;viles: <a href=\"http:\/\/www.carlosvergel.com\/03-algunavez.mp3\">www.carlosvergel.com\/03-algunavez.mp3<\/a><\/p>\n<p>Aqu&iacute; pueden descargar el &aacute;lbum completo &ldquo;Polos opuestos&rdquo; desde PC: <a href=\"http:\/\/www.carlosvergel.com\/cd_polosopuestos.zip\">www.carlosvergel.com\/cd_polosopuestos.zip<\/a><\/p>\n<p>\n\t<strong>Contacto<br \/>\n\tRoad Manager: LUIS LINDANTE<br \/>\n\tTel&eacute;fonos: (316)6194900, (04246)8287121<\/strong><\/p>\n<p><strong>E-Mail: <a href=\"mailto:prensa@carlosvergel.com\">prensa@carlosvergel.com<\/a><br \/>\n\tSitio Web: <a href=\"http:\/\/www.carlosvergel.com\">www.carlosvergel.com<\/a><\/strong><\/p>\n<p><strong>Redes Sociales<br \/>\n\tTwitter: @CARLOS_VERGEL \/ @RUBENCHO_R<br \/>\n\tFacebook: CARLOS VERGEL \/ RUBENCHO RODRIGUEZ<br \/>\n\tYouTube: CARLOSVERGELTV<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias al &eacute;xito que ha tenido el &aacute;lbum &ldquo;Polos opuestos&rdquo; de Carlos Vergel y Rub&eacute;n Rodr&iacute;gyez, se han ido concretando varias presentaciones en Colombia y Venezuela, donde podr&aacute;n mostrar en vivo con toda su agrupaci&oacute;n la propuesta musical con la cual han logrado sobresalir como nuevos exponentes del vallenato rom&aacute;ntico. Por ello ya est&aacute; en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/9799"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=9799"}],"version-history":[{"count":2,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/9799\/revisions"}],"predecessor-version":[{"id":9802,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/9799\/revisions\/9802"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/9800"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=9799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=9799"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=9799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}