{"id":9879,"date":"2013-05-09T21:49:59","date_gmt":"2013-05-10T02:49:59","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=9879"},"modified":"2013-05-09T21:49:59","modified_gmt":"2013-05-10T02:49:59","slug":"omar-geles-en-la-segunda-semana-de-exitos-de-gira-musical-por-ecuador","status":"publish","type":"post","link":"http:\/\/intervallenato.com\/inicio\/omar-geles-en-la-segunda-semana-de-exitos-de-gira-musical-por-ecuador\/","title":{"rendered":"Omar Geles, en la segunda semana de \u00e9xitos de gira musical por Ecuador"},"content":{"rendered":"<p style=\"text-align: justify;\">Omar Geles, el Cantautor m&aacute;s exitoso de Colombia, sigue de gira musical en Ecuador luego de tener un rotundo &eacute;xito con sus conciertos el pasado fin de semana.<\/p>\n<p style=\"text-align: justify;\">Omar Geles sigue en la presente semana en Ecuador y actuar&aacute; &eacute;ste viernes en Puyo y el domingo 13 en Macas, dos ciudades donde existe una gran expectativa por sus conciertos.<\/p>\n<p style=\"text-align: justify;\">El Cantautor, quien estuvo en Quito y Guayaquil, siendo ovacionado por m&aacute;s de 20 mil personas, cosecha triunfos en el vecino pa&iacute;s donde tiene una gran fanaticada.<\/p>\n<p style=\"text-align: justify;\">Omar Geles interpretar&aacute; sus obras como &lsquo;Los Caminos de la vida&rsquo; el m&aacute;s sentido homenaje a las Madres y los &eacute;xitos de su &aacute;lbum &lsquo;Hist&oacute;rico&rsquo;, donde se destacan &lsquo;No hay amor como t&uacute; amor&rsquo;, &lsquo;El vacilador&rsquo;, entre otros.<\/p>\n<p style=\"text-align: justify;\"><strong>Gira Musical<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Viernes 11 de mayo en Puyo<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Lunes 13: Macas<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>CONTACTOS:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Erick Ger&oacute;nimo &ndash; Manager<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>3012412661<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Omar Geles, el Cantautor m&aacute;s exitoso de Colombia, sigue de gira musical en Ecuador luego de tener un rotundo &eacute;xito con sus conciertos el pasado fin de semana. Omar Geles sigue en la presente semana en Ecuador y actuar&aacute; &eacute;ste viernes en Puyo y el domingo 13 en Macas, dos ciudades donde existe una gran [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/9879"}],"collection":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=9879"}],"version-history":[{"count":1,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/9879\/revisions"}],"predecessor-version":[{"id":9881,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/9879\/revisions\/9881"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/9880"}],"wp:attachment":[{"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=9879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=9879"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=9879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}