{"id":20040,"date":"2018-06-06T16:23:37","date_gmt":"2018-06-06T21:23:37","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=20040"},"modified":"2018-06-06T16:23:53","modified_gmt":"2018-06-06T21:23:53","slug":"peter-manjarres-y-juancho-de-la-espriella-siguen-cosechando-exitos","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/peter-manjarres-y-juancho-de-la-espriella-siguen-cosechando-exitos\/","title":{"rendered":"Peter Manjarr\u00e9s y Juancho de la Espriella\u00a0siguen cosechando \u00e9xitos"},"content":{"rendered":"<p><b>Los artistas vallenatos continuan su gira musical en todo el pa\u00eds, esta vez Neiva, la capital del departamento del\u00a0Huila se prepara para recibir este fin de semana &#8216;Caballero&#8217; Peter Manjarr\u00e9s y Juancho de la Espriella\u00a0con su \u00e9xito\u00a0musical\u00a0 \u201cLa que no me conoce\u201d.<\/b><\/p>\n<p><b>Los artistas llegaran\u00a0a la \u00abcapital bambuquera de Colombia\u00bb para ser la cuota vallenata de un importante concierto en donde alternar\u00e1 con la nueva figura de la m\u00fasica Pop Urbana,\u00a0Greeicy Rend\u00f3n,\u00a0y artistas destacados del g\u00e9nero urbano como\u00a0Wolfine\u00a0y\u00a0Golpe a Golpe.<\/b><\/p>\n<p><strong>\u00a0<\/strong><strong>El Caballero del Vallenato\u00a0Peter Manjarr\u00e9s &amp; Juancho de la Espriella\u00a0luego de actuar el pasado fin de semana en la capital del Pa\u00eds, donde dieron un excepcional concierto ante m\u00e1s de cinco mil personas de la familia corazonista que disfrutaron del impecable show de\u00a0Peter &amp; Juancho. All\u00ed, grandes y chicos gozaron de principio a fin con cada uno de los \u00e9xitos de la carrera musical de\u00a0Peter Manjarr\u00e9s, ratificando que su m\u00fasica trasciende en todas las generaciones.\u00a0Raz\u00f3n por la cual, semana a semana se disponen a complacer a todos sus seguidores<\/strong><\/p>\n<div id='gallery-1' class='gallery galleryid-20040 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/intervallenato.com\/inicio\/peter-manjarres-y-juancho-de-la-espriella-siguen-cosechando-exitos\/whatsapp-image-2018-06-06-at-3-08-30-pm\/'><img width=\"300\" height=\"200\" src=\"https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-300x200.jpeg 300w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-450x300.jpeg 450w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/intervallenato.com\/inicio\/peter-manjarres-y-juancho-de-la-espriella-siguen-cosechando-exitos\/whatsapp-image-2018-06-06-at-3-08-30-pm-1\/'><img width=\"300\" height=\"200\" src=\"https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-1-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-1-300x200.jpeg 300w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-1-768x512.jpeg 768w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-1-1024x682.jpeg 1024w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-1-450x300.jpeg 450w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.30-PM-1.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/intervallenato.com\/inicio\/peter-manjarres-y-juancho-de-la-espriella-siguen-cosechando-exitos\/whatsapp-image-2018-06-06-at-3-08-29-pm\/'><img width=\"300\" height=\"200\" src=\"https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.29-PM-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.29-PM-300x200.jpeg 300w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.29-PM-768x512.jpeg 768w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.29-PM-1024x682.jpeg 1024w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.29-PM-450x300.jpeg 450w, https:\/\/intervallenato.com\/inicio\/wp-content\/uploads\/2018\/06\/WhatsApp-Image-2018-06-06-at-3.08.29-PM.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>AGENDA DE CONCIERTOS<\/strong><\/p>\n<p><strong>-S\u00e1bado, 09 de Junio: Concierto Ol\u00e9 Festival. Neiva\u00a0(Huila)<\/strong><\/p>\n<p><strong>&#8211; Domingo, 10 de Junio: Fiestas del Sagrado Coraz\u00f3n. Betulia (Santander)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los artistas vallenatos continuan su gira musical en todo el pa\u00eds, esta vez Neiva, la capital del departamento del\u00a0Huila se prepara para recibir este fin de semana &#8216;Caballero&#8217; Peter Manjarr\u00e9s y Juancho de la Espriella\u00a0con su \u00e9xito\u00a0musical\u00a0 \u201cLa que no me conoce\u201d. Los artistas llegaran\u00a0a la \u00abcapital bambuquera de Colombia\u00bb para ser la cuota vallenata [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[21,15,14],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/20040"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=20040"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/20040\/revisions"}],"predecessor-version":[{"id":20044,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/20040\/revisions\/20044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/20041"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=20040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=20040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=20040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}