{"id":29491,"date":"2021-07-16T08:13:02","date_gmt":"2021-07-16T13:13:02","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=29491"},"modified":"2021-07-16T08:13:02","modified_gmt":"2021-07-16T13:13:02","slug":"alex-manga-continua-su-gira-por-estados-unidos","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/alex-manga-continua-su-gira-por-estados-unidos\/","title":{"rendered":"Alex Manga contin\u00faa su gira por Estados Unidos"},"content":{"rendered":"<p class=\"p1\">El artista Alex Manga contin\u00faa su segunda semana de conciertos en Estados Unidos donde ha tenido un rotundo \u00e9xito.<\/p>\n<p class=\"p1\"><span class=\"s1\">Alex Manga tendr\u00e1 la siguiente gira musical: <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 16 de julio: Dallas <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 17: Ciudad de M\u00e9xico &#8211; privado <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Domingo 18: San Jos\u00e9 &#8211; California &#8211; EE UU <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 23: FT Lauderdale <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 24: New Jersey <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">En estos escenarios, Alex Manga interpretar\u00e1 sus \u00e9xitos: No te vayas, A pesar de todo, No voy a llorar, Novios cruzados, Busca un confidente, La v\u00edctima del cuento y Hoja en blanco, entre otros. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Alex Manga es uno artistas del vallenato m\u00e1s solicitado en Estados Unidos, pa\u00eds donde realiza anualmente unos 40 conciertos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El artista Alex Manga contin\u00faa su segunda semana de conciertos en Estados Unidos donde ha tenido un rotundo \u00e9xito. Alex Manga tendr\u00e1 la siguiente gira musical: Viernes 16 de julio: Dallas S\u00e1bado 17: Ciudad de M\u00e9xico &#8211; privado Domingo 18: San Jos\u00e9 &#8211; California &#8211; EE UU Viernes 23: FT Lauderdale S\u00e1bado 24: New Jersey [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/29491"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=29491"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/29491\/revisions"}],"predecessor-version":[{"id":29492,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/29491\/revisions\/29492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/29442"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=29491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=29491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=29491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}