{"id":32030,"date":"2022-06-16T09:40:30","date_gmt":"2022-06-16T14:40:30","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=32030"},"modified":"2022-06-16T09:00:39","modified_gmt":"2022-06-16T14:00:39","slug":"diego-daza-va-con-el-reto-de-llenar-todos-los-escenarios-en-su-gira-por-estados-unidos","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/diego-daza-va-con-el-reto-de-llenar-todos-los-escenarios-en-su-gira-por-estados-unidos\/","title":{"rendered":"Diego Daza va con el reto de llenar todos los escenarios en su gira por Estados Unidos"},"content":{"rendered":"<p class=\"p1\">Llenar cada uno de los escenarios en su gira por Estados Unidos, es el nuevo reto del cantante Diego Daza, quien ya empez\u00f3 a motivar a sus seguidores por las redes sociales.<\/p>\n<p class=\"p1\"><span class=\"s1\">Diego Daza expresa en un reciente video: \u00abmi gente tenemos un nuevo reto de lograr un sold out en Miami, solos; el pr\u00f3ximo 6 de agosto; nos vemos en Cachita\u00bb.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La nueva gira de Diego Daza y su acordeonero Carlos Rueda ser\u00e1 en los meses de agosto, septiembre y octubre.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">As\u00ed es la agenda musical:<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"> S\u00e1bado 6 de agosto: Cachita &#8211; Miami<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 19: Vallenato Fest en Houston<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 20: Vallenato Fest en Dallas<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 2 de septiembre: Salt Lake City<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 3 de septiembre: San Jos\u00e9 de California <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 30 de septiembre: Atlanta <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 1 de octubre: Orlando<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 7 de octubre: New York <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 8 de octubre: New Jersey<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Diego Daza interpretar\u00e1 los \u00e9xitos de su \u00e1lbum &#8216;De Pel\u00edcula&#8217; que sigue metido en el coraz\u00f3n de los latinos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llenar cada uno de los escenarios en su gira por Estados Unidos, es el nuevo reto del cantante Diego Daza, quien ya empez\u00f3 a motivar a sus seguidores por las redes sociales. Diego Daza expresa en un reciente video: \u00abmi gente tenemos un nuevo reto de lograr un sold out en Miami, solos; el pr\u00f3ximo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32031,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32030"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=32030"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32030\/revisions"}],"predecessor-version":[{"id":32032,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32030\/revisions\/32032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/32031"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=32030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=32030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=32030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}