{"id":32052,"date":"2022-06-17T13:42:35","date_gmt":"2022-06-17T18:42:35","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=32052"},"modified":"2022-06-17T13:42:35","modified_gmt":"2022-06-17T18:42:35","slug":"hebert-vargas-alex-manga-y-luis-mateus-en-el-vallenatazo-en-monterrey-mexico","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/hebert-vargas-alex-manga-y-luis-mateus-en-el-vallenatazo-en-monterrey-mexico\/","title":{"rendered":"Hebert Vargas, Alex Manga y Luis Mateus, en el Vallenatazo en Monterrey &#8211; M\u00e9xico"},"content":{"rendered":"<p class=\"p1\">Con la presentaci\u00f3n de los cantantes Hebert Vargas, Alex Manga y Luis Mateus, se realizar\u00e1 el Vallenatazo este s\u00e1bado 18 de junio en la Arena Monterrey en M\u00e9xico.<\/p>\n<p class=\"p1\"><span class=\"s1\">Los artistas vallenatos ofrecieron una rueda de prensa y expresaron su satisfacci\u00f3n de estar nuevamente en la ciudad de Monterrey, donde su coraz\u00f3n palpita al ritmo de vallenato.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00c9xitos como: Paro de mi coraz\u00f3n, Acu\u00e9rdate, Inocente, No te vayas, Busca un confidente, Me tiraste al mar y Sin ti no hay vida, har\u00e1n parte del selecto repertorio de estos artistas.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El Vallenatazo es un espect\u00e1culo organizado por la empresa Monterrey Music con el fin de alegrar a los regiomontanos que siempre deliran con los cantos y acordeones.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la presentaci\u00f3n de los cantantes Hebert Vargas, Alex Manga y Luis Mateus, se realizar\u00e1 el Vallenatazo este s\u00e1bado 18 de junio en la Arena Monterrey en M\u00e9xico. Los artistas vallenatos ofrecieron una rueda de prensa y expresaron su satisfacci\u00f3n de estar nuevamente en la ciudad de Monterrey, donde su coraz\u00f3n palpita al ritmo de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32054,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32052"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=32052"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32052\/revisions"}],"predecessor-version":[{"id":32055,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32052\/revisions\/32055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/32054"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=32052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=32052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=32052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}