{"id":32157,"date":"2022-07-01T06:47:19","date_gmt":"2022-07-01T11:47:19","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=32157"},"modified":"2022-07-01T06:47:19","modified_gmt":"2022-07-01T11:47:19","slug":"alex-manga-inicia-el-tour-europa-2022-por-espana-inglaterra-italia-francia-y-suiza","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/alex-manga-inicia-el-tour-europa-2022-por-espana-inglaterra-italia-francia-y-suiza\/","title":{"rendered":"Alex Manga, inicia el tour Europa 2022, por Espa\u00f1a, Inglaterra, Italia, Francia y Suiza"},"content":{"rendered":"<p class=\"p1\">El artista Alex Manga, nuevamente emprende vuelo hacia el Viejo Continente para iniciar su tour \u2018Europa 2022\u2019, con 13 conciertos en los pa\u00edses de Espa\u00f1a, Inglaterra, Italia, Francia y Suiza.<\/p>\n<p class=\"p1\"><span class=\"s1\">Sin duda alguna, Alex Manga, lleva en su canto la representaci\u00f3n del folclor vallenato y esa bandera tricolor de Colombia que se agitar\u00e1 al ritmo de sus canciones para seguir cautivando al p\u00fablico europeo, latino y compatriotas que esperan con ansias este reencuentro.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Canciones como: Busca un confidente, Recuerdo de un amor, No te vayas, Me tiraste al mar, y Novios cruzados, har\u00e1n parte del selecto repertorio musical para cautivar a los europeos.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Manuel Polo, manager de Alex Manga, dio a conocer la gira musical del tour Europa 2022:<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 1 de julio: Discoteca La Cantera \u2013 Madrid \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 2: Latin Fest \u2013 Mil\u00e1n \u2013 Italia<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 8: The Royal Regency Reino Unido \u2013 Londres \u2013 Inglaterra<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 9: Sala The One \u2013 Alicante \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Domingo 10: Finca Los Felices \u2013 Murcia \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 15: Sala Santana \u2013 Bilbao \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 16: Even Center Ramada \u2013 Ginebra \u2013 Suiza<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Domingo 17: Discoteca Safari \u2013 Barcelona \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 22: Sala Rep\u00fablica \u2013 Valencia \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 23: Space Noisy Le Sec \u2013 Par\u00eds \u2013 Francia<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Domingo 24: La Cantina Delux \u2013 Mallorca \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 29: Tropical Palace Canarias \u2013 Las Palmas \u2013 Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 30: Xanadu \u2013 Canarias \u2013 Tenerife &#8211; Espa\u00f1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Indiscutiblemente, Alex Manga, es un cantante que cruza fronteras para dejar en alto el nombre de Colombia con la m\u00fasica vallenata.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El artista Alex Manga, nuevamente emprende vuelo hacia el Viejo Continente para iniciar su tour \u2018Europa 2022\u2019, con 13 conciertos en los pa\u00edses de Espa\u00f1a, Inglaterra, Italia, Francia y Suiza. Sin duda alguna, Alex Manga, lleva en su canto la representaci\u00f3n del folclor vallenato y esa bandera tricolor de Colombia que se agitar\u00e1 al ritmo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32157"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=32157"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32157\/revisions"}],"predecessor-version":[{"id":32159,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32157\/revisions\/32159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/32158"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=32157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=32157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=32157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}