{"id":32183,"date":"2022-07-05T16:27:11","date_gmt":"2022-07-05T21:27:11","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=32183"},"modified":"2022-07-05T16:27:11","modified_gmt":"2022-07-05T21:27:11","slug":"fabian-corrales-el-cantautor-de-moda-por-toda-colombia","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/fabian-corrales-el-cantautor-de-moda-por-toda-colombia\/","title":{"rendered":"Fabi\u00e1n Corrales, el cantautor de moda por toda Colombia"},"content":{"rendered":"<p class=\"p1\">Los aplausos se hicieron sentir en las cuatro presentaciones del cantautor original Fabi\u00e1n Corrales, en Valledupar y\u00a0 Bucaramanga<\/p>\n<p class=\"p1\"><span class=\"s1\">Fabi\u00e1n Corrales est\u00e1 de moda en los eventos p\u00fablicos y privados.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Es que Fabi\u00e1n Corrales cuando interpreta canciones como: T\u00fa norte soy yo, La Consentida y Ella tiene todo, la gente revive momentos importantes de su vida.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El artista orgullo de Urumita (Guajira) de mantiene de moda en las fiestas de Colombia.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Fabi\u00e1n Corrales estar\u00e1 en el el Festival de la Frontera en Maicao (Guajira) el jueves 14 de julio, en la nueva fecha de este certamen folcl\u00f3rico.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los aplausos se hicieron sentir en las cuatro presentaciones del cantautor original Fabi\u00e1n Corrales, en Valledupar y\u00a0 Bucaramanga Fabi\u00e1n Corrales est\u00e1 de moda en los eventos p\u00fablicos y privados. Es que Fabi\u00e1n Corrales cuando interpreta canciones como: T\u00fa norte soy yo, La Consentida y Ella tiene todo, la gente revive momentos importantes de su vida. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32183"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=32183"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32183\/revisions"}],"predecessor-version":[{"id":32184,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/32183\/revisions\/32184"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=32183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=32183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=32183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}