{"id":33038,"date":"2022-10-13T09:20:07","date_gmt":"2022-10-13T14:20:07","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=33038"},"modified":"2022-10-13T09:07:27","modified_gmt":"2022-10-13T14:07:27","slug":"el-rey-vallenato-nafer-duran-le-fue-implantado-un-marcapaso","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/el-rey-vallenato-nafer-duran-le-fue-implantado-un-marcapaso\/","title":{"rendered":"El rey vallenato N\u00e1fer Dur\u00e1n le fue implantado un marcapaso"},"content":{"rendered":"<p class=\"p1\">El rey vallenato de 1976, N\u00e1fer Dur\u00e1n hoy ser\u00e1 dado de alta en el Instituto Cardiovascular del Cesar en Valledupar, donde le implantaron un marcapaso.<\/p>\n<p class=\"p1\"><span class=\"s1\">El compositor Luis Dur\u00e1n Escorcia, hijo del juglar vallenato de 90 a\u00f1os de edad, explic\u00f3 que su padre sufri\u00f3 el pasado domingo una descompensaci\u00f3n mientras asist\u00eda a una iglesia en el municipio de El Paso, norte del Cesar.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El lunes 10 de octubre, N\u00e1fer Dur\u00e1n, asisti\u00f3 a una cita con el cardi\u00f3logo Oscar Guti\u00e9rrez de Pi\u00f1eres en Valledupar y se le detect\u00f3 una deficiencia card\u00edaca.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Posteriormente fue ingresado al centro asistencial donde le implantaron el marcapaso y su recuperaci\u00f3n ha sido satisfactoria.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El marcapaso es un peque\u00f1o dispositivo operado con pilas que percibe cuando el coraz\u00f3n est\u00e1 latiendo irregularmente o en forma muy lenta. Este env\u00eda una se\u00f1al al coraz\u00f3n que lo hace latir al ritmo correcto. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">N\u00e1fer Dur\u00e1n, hermano del primer rey vallenato, Alejo Dur\u00e1n, grab\u00f3 la destacada producci\u00f3n musical &#8216;Herencia Vallenata&#8217; al lado de Diomedes Diaz, impactando con los \u00e9xitos &#8216;El chanchullito&#8217; y &#8216;Los amores Teresita&#8217;.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El maestro N\u00e1fer Dur\u00e1n, quien reside en Valledupar, es un juglar vallenato integral que canta, toca acorde\u00f3n, compone y versea.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rey vallenato de 1976, N\u00e1fer Dur\u00e1n hoy ser\u00e1 dado de alta en el Instituto Cardiovascular del Cesar en Valledupar, donde le implantaron un marcapaso. El compositor Luis Dur\u00e1n Escorcia, hijo del juglar vallenato de 90 a\u00f1os de edad, explic\u00f3 que su padre sufri\u00f3 el pasado domingo una descompensaci\u00f3n mientras asist\u00eda a una iglesia en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33039,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33038"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=33038"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33038\/revisions"}],"predecessor-version":[{"id":33040,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33038\/revisions\/33040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/33039"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=33038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=33038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=33038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}