{"id":33057,"date":"2022-10-14T07:47:44","date_gmt":"2022-10-14T12:47:44","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=33057"},"modified":"2022-10-14T07:47:44","modified_gmt":"2022-10-14T12:47:44","slug":"juez-de-hatonuevo-declaro-improcedente-tutela-contra-la-novela-de-leandro-diaz","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/juez-de-hatonuevo-declaro-improcedente-tutela-contra-la-novela-de-leandro-diaz\/","title":{"rendered":"Juez de Hatonuevo declar\u00f3 improcedente tutela contra la novela de Leandro Diaz"},"content":{"rendered":"<p class=\"p1\">El Juzgado Primero Promiscuo de Hatonuevo (Guajira) declar\u00f3 improcedente la acci\u00f3n de tutela contra la novela de Leandro Diaz que se emite por el canal de RCN.<\/p>\n<p class=\"p1\"><span class=\"s1\">Los accionantes pretend\u00edan que se eliminaran unos cap\u00edtulos de la novela Leandro Diaz y se suspendiera su emisi\u00f3n porque no estaba ajustada a la realidad.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Carmen Sof\u00eda Diaz Diaz, en representacion de sus familiares Ledis Diaz, Arinda Diaz, Dorismel Diaz y Wilder Duarte Diaz, hermana y sobrinos del juglar vallenato, argumentaron que la producci\u00f3n de televisi\u00f3n vulnera sus derechos y atenta contra el buen nombre de la familia y personas fallecidas como: Abel Duarte (Onofre Duarte en la novela) y Nicolasa Diaz (Tomasa en la tv).<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La molestia de los Diaz, es porque en la novela se muestra a Abel Duarte con un car\u00e1cter fuerte, maltratando a Leandro Diaz cuando era ni\u00f1o; muestran<span class=\"Apple-converted-space\">\u00a0 <\/span>infidelidades, vocabulario grosero y no se respet\u00f3 la vida \u00edntima.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El cantante Ivo Diaz, hijo de Leandro Diaz, le pidi\u00f3 al juez desconocer la legitimidad de los accionantes ya que su parentesco no est\u00e1 comprobado.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La novela de Leandro Diaz tiene como protagonista al cantante Silvestre Dangond, quien termin\u00f3 la grabaci\u00f3n de 80 cap\u00edtulos y se encuentra en los primeros lugares de sinton\u00eda.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Juzgado Primero Promiscuo de Hatonuevo (Guajira) declar\u00f3 improcedente la acci\u00f3n de tutela contra la novela de Leandro Diaz que se emite por el canal de RCN. Los accionantes pretend\u00edan que se eliminaran unos cap\u00edtulos de la novela Leandro Diaz y se suspendiera su emisi\u00f3n porque no estaba ajustada a la realidad. Carmen Sof\u00eda Diaz [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33058,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33057"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=33057"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33057\/revisions"}],"predecessor-version":[{"id":33059,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33057\/revisions\/33059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/33058"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=33057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=33057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=33057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}