{"id":33086,"date":"2022-10-18T10:40:27","date_gmt":"2022-10-18T15:40:27","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=33086"},"modified":"2022-10-18T09:20:25","modified_gmt":"2022-10-18T14:20:25","slug":"martin-elias-jr-quiere-ser-cantante","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/martin-elias-jr-quiere-ser-cantante\/","title":{"rendered":"Martin Elias Jr quiere ser cantante"},"content":{"rendered":"<p class=\"p1\">A sus 14 a\u00f1os de edad, Mart\u00edn Elias Jr., hijo del gran Mart\u00edn Elias (Qepd), tom\u00f3 la firme decisi\u00f3n aprender a cantar vallenato para seguir el legado de la dinast\u00eda Diaz.<\/p>\n<p class=\"p1\"><span class=\"s1\">Mart\u00edn Elias Jr, se encuentra en Valledupar recibiendo clases de canto en la academia del acordeonero Jos\u00e9 Fernando &#8216;El Morre&#8217; Romero.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00abEn nuestro 5 d\u00eda de clases; ah\u00ed vamos poco a poco Mart\u00edn Elias Jr., con disciplina se llega lejos. Vamos por m\u00e1s en este inicio de clases vocales con Dios de la mano. Aqu\u00ed estamos firmes trabajando por este sue\u00f1o que pronto se cristalizar\u00e1\u00bb, escribi\u00f3 &#8216;El Morre&#8217; Romero en su cuenta de Instagram.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Mart\u00edn Elias Jr. coment\u00f3 \u00abeste es un proceso que requiere mucha disciplina y disfruto cada momento. El tiempo de mi preparaci\u00f3n en el canto lo lleva Dios\u00bb.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">En un video publicado, el joven interpreta en el ensayo las canciones<span class=\"Apple-converted-space\">\u00a0 <\/span>&#8216;Sin medir distancia&#8217; y &#8216;El ahijado&#8217;, mostrando sus ganas para seguir avanzando.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Por su parte, Elder Day\u00e1n, t\u00edo de Mart\u00edn, lo anim\u00f3 para que siga adelante y que cuenta con todo su respaldo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sus 14 a\u00f1os de edad, Mart\u00edn Elias Jr., hijo del gran Mart\u00edn Elias (Qepd), tom\u00f3 la firme decisi\u00f3n aprender a cantar vallenato para seguir el legado de la dinast\u00eda Diaz. Mart\u00edn Elias Jr, se encuentra en Valledupar recibiendo clases de canto en la academia del acordeonero Jos\u00e9 Fernando &#8216;El Morre&#8217; Romero. \u00abEn nuestro 5 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33088,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33086"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=33086"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33086\/revisions"}],"predecessor-version":[{"id":33089,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33086\/revisions\/33089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/33088"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=33086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=33086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=33086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}