{"id":33444,"date":"2022-11-24T13:29:29","date_gmt":"2022-11-24T18:29:29","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=33444"},"modified":"2022-11-24T13:29:29","modified_gmt":"2022-11-24T18:29:29","slug":"hoy-esta-de-cumpleanos-el-cantante-osnaider-brito","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/hoy-esta-de-cumpleanos-el-cantante-osnaider-brito\/","title":{"rendered":"Hoy est\u00e1 de cumplea\u00f1os el cantante Osnaider Brito"},"content":{"rendered":"<p class=\"p1\">El cantante Osnaider Brito, quien fue el vocalista l\u00edder de la agrupaci\u00f3n de Los Muchachos, hoy se encuentra de cumplea\u00f1os y celebra esta fecha especial con sus familiares, amigos y seguidores.<\/p>\n<p class=\"p1\"><span class=\"s1\">Osnaider Brito integr\u00f3 al lado del acordeonero Gabriel &#8216;El Chiche&#8217; Maestre, la agrupaci\u00f3n Los Muchachos con sede en Barranquilla, logrando su impacto musical con la canci\u00f3n &#8216;Volver a la ternura&#8217; de la autor\u00eda de Iv\u00e1n Ovalle en 1989 con el \u00e1lbum &#8216;Fascinante&#8217;. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Posteriormente Los Muchachos grabaron los elep\u00e9s: &#8216;Fiesta de Colores&#8217;, &#8216;Una rosa para ti&#8217;,<span class=\"Apple-converted-space\">\u00a0 <\/span>&#8216;Que nota&#8217;, y &#8216;Mundiales&#8217;, consolidando este proyecto musical.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Osnaider Brito luego grab\u00f3 con Juan Jos\u00e9 Granados, el \u00e1lbum &#8216;Voy a publicar estos amores&#8217;. Sigui\u00f3 con Gregorio &#8216;Goyo&#8217; Oviedo con el trabajo &#8216;Pru\u00e9bame&#8217; en 1998. Con Wilber Mendoza grab\u00f3 la producci\u00f3n &#8216;Desde Valledupar&#8217;; y<span class=\"Apple-converted-space\">\u00a0 <\/span>con el acordeonero Santa Orozco hizo el \u00e1lbum &#8216;Incompatibles&#8217;.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Osnaider Brito naci\u00f3 en Ca\u00f1averales, municipio de San Juan del Cesar (Guajira) y conserva su estilo, su voz y calidad art\u00edstica.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Feliz cumplea\u00f1os para Osnaider Brito y que los cumplas feliz muy feliz&#8230;<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">*Servicio Informativo de Intervallenato.com*<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">*Paul Bola\u00f1o Saurith*<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">*Cel.: 3157494904*<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante Osnaider Brito, quien fue el vocalista l\u00edder de la agrupaci\u00f3n de Los Muchachos, hoy se encuentra de cumplea\u00f1os y celebra esta fecha especial con sus familiares, amigos y seguidores. Osnaider Brito integr\u00f3 al lado del acordeonero Gabriel &#8216;El Chiche&#8217; Maestre, la agrupaci\u00f3n Los Muchachos con sede en Barranquilla, logrando su impacto musical con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33444"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=33444"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33444\/revisions"}],"predecessor-version":[{"id":33446,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/33444\/revisions\/33446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/33445"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=33444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=33444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=33444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}