{"id":34094,"date":"2023-02-08T15:48:11","date_gmt":"2023-02-08T20:48:11","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=34094"},"modified":"2023-02-08T15:48:11","modified_gmt":"2023-02-08T20:48:11","slug":"murio-el-directivo-de-sayco-armando-romero-molina","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/murio-el-directivo-de-sayco-armando-romero-molina\/","title":{"rendered":"Muri\u00f3 el Directivo de Sayco, Armando Romero Molina"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">El directivo de Sayco, Armando Romero Molina muri\u00f3 de un infarto esta tarde en las oficinas de la entidad en el norte de Bogot\u00e1.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Compa\u00f1eros de trabajo llamaron una ambulancia para prestarle los primeros auxilios pero lamentablemente falleci\u00f3.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Armando Romero Molina fue compositor y entre sus canciones est\u00e1n: Cuando llego en temple, La hembra perfecta, Se acab\u00f3 el jueguito y Siempre contigo.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El directivo de Sayco era oriundo de Urumita (Guajira) y ten\u00eda 63 a\u00f1os de edad. Paz en su tumba.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El directivo de Sayco, Armando Romero Molina muri\u00f3 de un infarto esta tarde en las oficinas de la entidad en el norte de Bogot\u00e1. Compa\u00f1eros de trabajo llamaron una ambulancia para prestarle los primeros auxilios pero lamentablemente falleci\u00f3. Armando Romero Molina fue compositor y entre sus canciones est\u00e1n: Cuando llego en temple, La hembra perfecta, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":34095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/34094"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=34094"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/34094\/revisions"}],"predecessor-version":[{"id":34096,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/34094\/revisions\/34096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/34095"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=34094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=34094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=34094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}