{"id":36003,"date":"2023-08-24T09:08:27","date_gmt":"2023-08-24T14:08:27","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=36003"},"modified":"2023-08-24T09:08:27","modified_gmt":"2023-08-24T14:08:27","slug":"ana-del-castillo-conquista-a-venezuela-y-a-colombia-con-su-canto","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/ana-del-castillo-conquista-a-venezuela-y-a-colombia-con-su-canto\/","title":{"rendered":"Ana del Castillo, conquista a Venezuela y a Colombia con su canto"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">La Bomba Sexy del Vallenato, Ana del Castillo conquista a Venezuela y a Colombia con su impecable canto y en la presente semana tendr\u00e1 cuatro presentaciones entre los dos pa\u00edses.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ana del Castillo, tendr\u00e1 la siguiente agenda musical:<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Jueves 24 de agosto: Sinamaica \u2013 Venezuela<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Viernes 25: Patillal \u2013 fiesta privada<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">S\u00e1bado 26: Montel\u00edbano \u2013 C\u00f3rdoba \u2013 privada<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Domingo 27: Festival del Retorno en Fonseca \u2013 La Guajira<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ana del Castillo sigue siendo la sensaci\u00f3n en cada escenario donde se presenta porque deslumbra con su voz, su carisma, sencillez y esa entrega total para complacer al publico que disfruta con sus canciones<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Bomba Sexy del Vallenato, Ana del Castillo conquista a Venezuela y a Colombia con su impecable canto y en la presente semana tendr\u00e1 cuatro presentaciones entre los dos pa\u00edses. Ana del Castillo, tendr\u00e1 la siguiente agenda musical: Jueves 24 de agosto: Sinamaica \u2013 Venezuela Viernes 25: Patillal \u2013 fiesta privada S\u00e1bado 26: Montel\u00edbano \u2013 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36004,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/36003"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=36003"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/36003\/revisions"}],"predecessor-version":[{"id":36005,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/36003\/revisions\/36005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/36004"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=36003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=36003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=36003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}