{"id":40056,"date":"2024-11-25T11:45:00","date_gmt":"2024-11-25T16:45:00","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=40056"},"modified":"2024-11-25T19:31:40","modified_gmt":"2024-11-26T00:31:40","slug":"silvestre-dangond-grabo-dvd-en-vivo-en-homenaje-al-rey-vallenato-chemita-ramos-en-urumita-la-guajira-su-tierra-natal","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/silvestre-dangond-grabo-dvd-en-vivo-en-homenaje-al-rey-vallenato-chemita-ramos-en-urumita-la-guajira-su-tierra-natal\/","title":{"rendered":"Silvestre Dangond grab\u00f3 DVD en vivo en homenaje al rey vallenato Chemita Ramos en Urumita \u2013 La Guajira, su tierra natal"},"content":{"rendered":"\n<p>El cantante Silvestre Dangond grab\u00f3 un DVD en vivo en homenaje al recordado d\u00e9cimo rey vallenato \u2018Chemita\u2019 Ramos, en la plaza principal de Urumita \u2013 La Guajira, su tierra natal, donde tuvo como invitados especiales a los herederos del juglar: Eduar y Chemita Ramos Jr.<\/p>\n\n\n\n<p>La producci\u00f3n se realiz\u00f3 en la plaza principal del pueblo, frente a la nueva casa colonial de Silvestre Dangond, interpretando esos cl\u00e1sicos del vallenato como: Norfidia, Lirio rojo, El Chevorlito, Carmen G\u00f3mez, Si yo supiera, El copet\u00f3n, El cocuyo, entre otros temas.<\/p>\n\n\n\n<p>Asimismo, estuvo como invitado el cantante Jos\u00e9 Enrique \u2018Chelo\u2019 Alvarado, quien acompa\u00f1\u00f3 por muchos a\u00f1os al d\u00e9cimo Chema Ramos (Qepd).<\/p>\n\n\n\n<p>Silvestre Dangond llev\u00f3 a toda su agrupaci\u00f3n musical con sus dos acordeoneros Jos\u00e9 Juan Camilo Guerra y Rub\u00e9n Lanao, actuando frente a un selecto p\u00fablico que estaba c\u00f3modamente sentado frente este pintoresco escenario colonial.<\/p>\n\n\n\n<p>El homenaje de Silvestre Dangond al d\u00e9cimo rey vallenato Chemita Ramos y su dinast\u00eda, saldr\u00e1 para finales del presente a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantante Silvestre Dangond grab\u00f3 un DVD en vivo en homenaje al recordado d\u00e9cimo rey vallenato \u2018Chemita\u2019 Ramos, en la plaza principal de Urumita \u2013 La Guajira, su tierra natal, donde tuvo como invitados especiales a los herederos del juglar: Eduar y Chemita Ramos Jr. La producci\u00f3n se realiz\u00f3 en la plaza principal del pueblo, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40057,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,55],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/40056"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=40056"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/40056\/revisions"}],"predecessor-version":[{"id":40058,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/40056\/revisions\/40058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/40057"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=40056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=40056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=40056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}