{"id":40317,"date":"2025-01-03T22:29:11","date_gmt":"2025-01-04T03:29:11","guid":{"rendered":"https:\/\/intervallenato.com\/inicio\/?p=40317"},"modified":"2025-01-03T22:29:12","modified_gmt":"2025-01-04T03:29:12","slug":"fabian-corrales-en-las-grandes-fiestas-de-colombia","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/fabian-corrales-en-las-grandes-fiestas-de-colombia\/","title":{"rendered":"Fabi\u00e1n Corrales en las grandes fiestas de Colombia"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>El Cantautor Original, Fabi\u00e1n Corrales inicia con pie derecho sus compromisos art\u00edsticos recorriendo las diferentes regiones de Colombia complaciendo a sus seguidores con sus grandes \u00e9xitos.<\/p>\n\n\n\n<p>Fabi\u00e1n Corrales y su acordeonero Leonardo \u2018Nano\u2019 Farf\u00e1n, tienen la siguiente agenda de presentaciones:<\/p>\n\n\n\n<p>Viernes 3 enero: Gamarra \u2013 Cesar<\/p>\n\n\n\n<p>S\u00e1bado 4: Valledupar \u2013 privado&nbsp;<\/p>\n\n\n\n<p>Lunes 6 de enero: Paz de Ariporo &#8211; Casanare<\/p>\n\n\n\n<p>En estas tres plazas, Fabi\u00e1n Corrales interpretar\u00e1 lo mejor de su repertorio musical con esas canciones que conquistan corazones como: T\u00fa norte soy yo, La consentida, El amor es as\u00ed, Orgullosa y Que te guste yo.<\/p>\n\n\n\n<p>En el 2025, Fabi\u00e1n Corrales est\u00e1 presente en las grandes fiestas de Colombia.<\/p>\n\n\n\n<p>*Sistema Informativo de Intervallenato*<\/p>\n\n\n\n<p>*Director \u2013 Paul Bola\u00f1o Saurith*<\/p>\n\n\n\n<p>*Cel: 3157494904*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cantautor Original, Fabi\u00e1n Corrales inicia con pie derecho sus compromisos art\u00edsticos recorriendo las diferentes regiones de Colombia complaciendo a sus seguidores con sus grandes \u00e9xitos. Fabi\u00e1n Corrales y su acordeonero Leonardo \u2018Nano\u2019 Farf\u00e1n, tienen la siguiente agenda de presentaciones: Viernes 3 enero: Gamarra \u2013 Cesar S\u00e1bado 4: Valledupar \u2013 privado&nbsp; Lunes 6 de enero: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40264,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,55],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/40317"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=40317"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/40317\/revisions"}],"predecessor-version":[{"id":40318,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/40317\/revisions\/40318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/40264"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=40317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=40317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=40317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}