{"id":8374,"date":"2012-11-13T08:49:16","date_gmt":"2012-11-13T13:49:16","guid":{"rendered":"http:\/\/intervallenato.com\/inicio\/?p=8374"},"modified":"2012-11-13T08:49:16","modified_gmt":"2012-11-13T13:49:16","slug":"peter-manjarres-y-sergio-luis-rodriguez-en-el-lanzamiento-de-la-telenovela-rafael-orozco-el-idolo","status":"publish","type":"post","link":"https:\/\/intervallenato.com\/inicio\/peter-manjarres-y-sergio-luis-rodriguez-en-el-lanzamiento-de-la-telenovela-rafael-orozco-el-idolo\/","title":{"rendered":"Peter Manjarres y Sergio Lu\u00eds Rodr\u00edguez en el lanzamiento de la telenovela &#8216;Rafael Orozco el \u00cddolo&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoy 13 de noviembre se llevar&aacute; a cabo en la capital del pa&iacute;s el lanzamiento para medios de la telenovela Rafael Orozco &lsquo;El &Iacute;dolo&rsquo;, que pr&oacute;ximamente saldr&aacute; al aire en el horario estelar del Canal Caracol. Peter Manjarr&eacute;s y Sergio Luis Rodr&iacute;guez estar&aacute;n present&aacute;ndose en este gran evento que se efectuar&aacute; en el restaurante Salto del &Aacute;ngel a las 8 de la noche. Cabe resaltar, que el Caballero del vallenato acept&oacute; la invitaci&oacute;n que le hizo el equipo de producci&oacute;n porque se considera el seguidor n&uacute;mero uno de Rafael Orozco por su canto y disciplina.<\/p>\n<p style=\"text-align: justify;\">A este importante acontecimiento asistir&aacute;n los miembros de la Junta directiva del Grupo Santo Domingo, personalidades de la far&aacute;ndula nacional, la pol&iacute;tica, periodistas y por supuesto el elenco de la novela que recrear&aacute; la historia de uno de los artistas m&aacute;s queridos y admirados por varias generaciones.<\/p>\n<p style=\"text-align: justify;\">Un show musical de primer nivel dirigido por el maestro Carlos Ag&uuml;era dar&aacute; apertura a una noche m&aacute;gica llena de romanticismo y alegr&iacute;a que adem&aacute;s contar&aacute; con la participaci&oacute;n de Jorge Celed&oacute;n, Jean Carlos Centeno y Pipe Bueno.<\/p>\n<p style=\"text-align: justify;\">Alejandro Palacio y Taliana Vargas son los protagonistas de esta historia que desde el semestre anterior empez&oacute; a grabarse en locaciones ubicadas en Valledupar y varios municipios del departamento del Cesar y La Guajira. Muy pronto los televidentes ver&aacute;n los resultados de un proyecto audiovisual que cautivar&aacute; a miles de<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fuente:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Representante Comercial:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Road Manager<\/strong><\/p>\n<p>RAFAEL D&Iacute;AZ RIVERO&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; MARCOS TORRES&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; HENRY CAICEDO&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Jefe de prensa&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Celular: 315 7338388 &#8211; 300 8140721&nbsp;&nbsp;&nbsp;&nbsp; Celular: 318 &#8211; 7428660&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<br \/>\n\t<a href=\"mailto:rdiaz@petermanjarres.net\">rdiaz@petermanjarres.net<\/a>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<a href=\"mailto:martovel@hotmail.com\">martovel@hotmail.com<\/a>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 314 &#8211; 5729972&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p style=\"margin-left: 177pt;\">Celular: 300 6092600 &#8211; 317 6668275&nbsp;&nbsp;&nbsp;&nbsp; <a href=\"mailto:mtorres@petermanjarres.net\">mtorres@petermanjarres.net<\/a><u>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; roadmanager@petermanjarres.net<\/u><\/p>\n<p style=\"margin-left: 177pt;\">@rafaeljosediaz&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;@Martovel&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;@HenryManager<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy 13 de noviembre se llevar&aacute; a cabo en la capital del pa&iacute;s el lanzamiento para medios de la telenovela Rafael Orozco &lsquo;El &Iacute;dolo&rsquo;, que pr&oacute;ximamente saldr&aacute; al aire en el horario estelar del Canal Caracol. Peter Manjarr&eacute;s y Sergio Luis Rodr&iacute;guez estar&aacute;n present&aacute;ndose en este gran evento que se efectuar&aacute; en el restaurante Salto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/8374"}],"collection":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/comments?post=8374"}],"version-history":[{"count":1,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/8374\/revisions"}],"predecessor-version":[{"id":8376,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/posts\/8374\/revisions\/8376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media\/8375"}],"wp:attachment":[{"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/media?parent=8374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/categories?post=8374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intervallenato.com\/inicio\/wp-json\/wp\/v2\/tags?post=8374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}